                       {"id":34260,"date":"2022-11-06T23:47:49","date_gmt":"2022-11-07T05:47:49","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=34260"},"modified":"2024-12-11T10:40:16","modified_gmt":"2024-12-11T16:40:16","slug":"atacan-hombres-armados-en-praderas-de-san-juan","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/atacan-hombres-armados-en-praderas-de-san-juan\/","title":{"rendered":"Atacan hombres armados en Praderas de San Juan"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.- Varios disparos de arma de fuego rompieron el silencio de la noche en la colonia Praderas de San Juan, en Ju\u00e1rez, Nuevo Le\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Los hechos ocurrieron a las 8:30 de la noche de hoy, cuando dos sujetos abordo de una motocicleta, atacaron a un hombre a tiros, quien se protegi\u00f3 dentro de su domicilio en la calle Badajo, entre la calle M\u00e1laga y Sevilla, de la mencionada colonia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-34262\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/11\/IMG-20221106-WA0108-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/11\/IMG-20221106-WA0108-300x225.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/11\/IMG-20221106-WA0108-1024x768.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/11\/IMG-20221106-WA0108-768x576.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/11\/IMG-20221106-WA0108.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Los agresores dispararaon a la fachada de la vivienda en al menos seis ocasiones, antes de escapar con rumbo desconocido.<\/p>\n<p>&nbsp;<\/p>\n<p>La v\u00edctima del atentado s\u00f3lo presentaba una leve herida en una ceja, que no requiri\u00f3 hospitalizaci\u00f3n.<\/p>\n<ol>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-34263\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/11\/IMG-20221106-WA0107-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/11\/IMG-20221106-WA0107-300x225.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/11\/IMG-20221106-WA0107-1024x768.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/11\/IMG-20221106-WA0107-768x576.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/11\/IMG-20221106-WA0107.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li>\n<\/ol>\n<p>Al lugar arribaron elementos de la polic\u00eda municipal para realizar las primeras investigaciones, as\u00ed como polic\u00edas ministeriales y Sevicios Periciales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Varios disparos de arma de fuego rompieron el silencio de la noche en la colonia Praderas de San Juan, en Ju\u00e1rez, Nuevo Le\u00f3n. &nbsp; Los hechos ocurrieron a las 8:30 de la noche de hoy, cuando dos sujetos abordo de una motocicleta, atacaron a un hombre a tiros, quien se protegi\u00f3 dentro de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":34261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[4346,4363],"class_list":["post-34260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-armas","tag-disparos"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/34260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=34260"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/34260\/revisions"}],"predecessor-version":[{"id":79187,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/34260\/revisions\/79187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/34261"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=34260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=34260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=34260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}