                       {"id":34511,"date":"2022-11-15T15:36:01","date_gmt":"2022-11-15T21:36:01","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=34511"},"modified":"2024-12-11T10:40:17","modified_gmt":"2024-12-11T16:40:17","slug":"supervisa-paco-trevino-obra-pluvial-en-la-12-de-octubre","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/supervisa-paco-trevino-obra-pluvial-en-la-12-de-octubre\/","title":{"rendered":"Supervisa Paco Trevi\u00f1o obra pluvial en la 12 de Octubre"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.- El dia de hoy, el alcalde de Ju\u00e1rez, Paco Trevi\u00f1o, supervis\u00f3 la obra de un canal pluvial que fue abierto en la colonia 12 de Octubre de esta ciudad, ya que en las \u00faltimas lluvias del mes de Septiembre esta colonia sufri\u00f3 una inundaci\u00f3n en sus \u00faltimas calles debido a que con la construcci\u00f3n del Perif\u00e9rico, toda el agua se canalizada a ese lugar que era insuficiente para su liberaci\u00f3n.<\/p>\n<p>La obra est\u00e1 ya por terminarse y puede observarse que el canal de 500 metros de largo, tiene una buena amplitud para evitar futuras inundaciones en el lugar; siendo la inversi\u00f3n en dicha obra de medio mill\u00f3n de pesos, ya que aparte de la canalizaci\u00f3n tambi\u00e9n se hizo entrega de unos bonos a cada uno de los habitantes afectados por la inundaci\u00f3n para la compra de enseres dom\u00e9sticos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- El dia de hoy, el alcalde de Ju\u00e1rez, Paco Trevi\u00f1o, supervis\u00f3 la obra de un canal pluvial que fue abierto en la colonia 12 de Octubre de esta ciudad, ya que en las \u00faltimas lluvias del mes de Septiembre esta colonia sufri\u00f3 una inundaci\u00f3n en sus \u00faltimas calles debido a que con la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":34512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[3590,4903,1684,5141],"class_list":["post-34511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-juarez-nl","tag-obra-pluvial","tag-paco-trevino","tag-supervisan"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/34511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=34511"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/34511\/revisions"}],"predecessor-version":[{"id":79309,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/34511\/revisions\/79309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/34512"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=34511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=34511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=34511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}