                       {"id":34667,"date":"2022-11-21T14:57:15","date_gmt":"2022-11-21T20:57:15","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=34667"},"modified":"2024-12-11T10:40:18","modified_gmt":"2024-12-11T16:40:18","slug":"detienen-a-homicida-de-rincon-del-parque","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/detienen-a-homicida-de-rincon-del-parque\/","title":{"rendered":"Detienen a homicida de Rincon del Parque"},"content":{"rendered":"<p>Juarez, N.L.- El pasado viernes elementos de la Subdirecci\u00f3n de Investigaci\u00f3n de Homicidios de la Agencia Estatal de Investigaciones realizaron la detenci\u00f3n de un hombre quien es el presunto responsable de un homicidio perpetrado el a\u00f1o pasado en la colonia Rinc\u00f3n del Parque del municipio de Ju\u00e1rez.<\/p>\n<p>El detenido fue identificado como Luis Alberto de 49 a\u00f1os de edad, quien fue detenido en Camino a la Paz en la colonia Joaquin Garza y Garza, cruce m\u00e1s pr\u00f3ximo al camino a Rancho el Curro en el municipio de Ju\u00e1rez, Nuevo Le\u00f3n.<\/p>\n<p>Esto para despu\u00e9s ser internado en el Centro de Reinserci\u00f3n Social N\u00famero 01 Norte, ubicado en la Carretera a Salinas Victoria Km 1.5, en el municipio de Apodaca, Nuevo Le\u00f3n; ya que es probable responsable de la Muerte Violenta de quien en vida llevar\u00e1 por nombre Jos\u00e9 Feliciano de 26 a\u00f1os en los hechos suscitados el d\u00eda S\u00e1bado 15 de Mayo de 2021, en la Colonia Rinc\u00f3n del Parque, puesto que en los datos obtenidos dentro de la investigaci\u00f3n, refieren que siendo el d\u00eda citado se encontraba la v\u00edctima hablando por tel\u00e9fono afuera de un domicilio, cuando de repente lleg\u00f3 el detenido con un arma de fuego entre sus manos y con la cual le comenz\u00f3 a disparar al ahora occiso, mismo que cay\u00f3 al suelo.<\/p>\n<p>Tras los hechos, el cuerpo de la victima fue trasladado a las instalaciones del SEMEFO para su respectiva autopsia de ley determinando los m\u00e9dicos legistas que la causa del deceso fueron lesiones intracraneales e intraabdominales secundarias a trayectos de proyectiles de arma de fuego.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juarez, N.L.- El pasado viernes elementos de la Subdirecci\u00f3n de Investigaci\u00f3n de Homicidios de la Agencia Estatal de Investigaciones realizaron la detenci\u00f3n de un hombre quien es el presunto responsable de un homicidio perpetrado el a\u00f1o pasado en la colonia Rinc\u00f3n del Parque del municipio de Ju\u00e1rez. El detenido fue identificado como Luis Alberto de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":34669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[819,1199,3590],"class_list":["post-34667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-detenido","tag-homicida","tag-juarez-nl"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/34667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=34667"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/34667\/revisions"}],"predecessor-version":[{"id":79383,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/34667\/revisions\/79383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/34669"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=34667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=34667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=34667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}