                       {"id":35752,"date":"2022-12-28T15:11:58","date_gmt":"2022-12-28T21:11:58","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=35752"},"modified":"2024-12-11T10:40:26","modified_gmt":"2024-12-11T16:40:26","slug":"el-tribunal-supremo-de-estados-unidos-rechaza-derogar-la-norma-que-permite-expulsar-migrantes-en-caliente","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/el-tribunal-supremo-de-estados-unidos-rechaza-derogar-la-norma-que-permite-expulsar-migrantes-en-caliente\/","title":{"rendered":"El Tribunal Supremo de Estados Unidos rechaza derogar la norma que permite expulsar migrantes en caliente"},"content":{"rendered":"<p>EUA.- El Tribunal Supremo de Estados Unidos ha resuelto este martes mantener en vigor el T\u00edtulo 42, una norma instaurada durante la presidencia de Donald Trump que permite la expulsi\u00f3n en caliente de migrantes de vuelta a M\u00e9xico.<br \/>\nTrump desempolv\u00f3 la medida, usada por primera vez en 1929 para contener la inmigraci\u00f3n asi\u00e1tica, arguyendo motivos sanitarios, al inicio de la pandemia.<br \/>\nLa idea era evitar la expansi\u00f3n del coronavirus en un momento en el que las fronteras por todo el mundo se cerraron. Casi tres a\u00f1os despu\u00e9s, con el virus razonablemente controlado (y las fronteras entre ambos pa\u00edses norteamericanos abiertas desde hace tiempo), la Administraci\u00f3n de Joe Biden recibe un nuevo varapalo en sus reiterados intentos de derogar la norma. Se trata del \u00faltimo rev\u00e9s judicial que la Casa Blanca recibe en su autonom\u00eda en materia de gesti\u00f3n migratoria. El Supremo, de mayor\u00eda conservadora, ha votado 5-4 a favor de mantener el T\u00edtulo 42. La decisi\u00f3n deja a miles de inmigrantes en el limbo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUA.- El Tribunal Supremo de Estados Unidos ha resuelto este martes mantener en vigor el T\u00edtulo 42, una norma instaurada durante la presidencia de Donald Trump que permite la expulsi\u00f3n en caliente de migrantes de vuelta a M\u00e9xico. Trump desempolv\u00f3 la medida, usada por primera vez en 1929 para contener la inmigraci\u00f3n asi\u00e1tica, arguyendo motivos [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":35753,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[5579,5578,3672],"class_list":["post-35752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-eua","tag-interncional","tag-migrantes"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/35752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=35752"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/35752\/revisions"}],"predecessor-version":[{"id":79935,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/35752\/revisions\/79935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/35753"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=35752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=35752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=35752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}