                       {"id":35826,"date":"2022-12-30T21:07:04","date_gmt":"2022-12-31T03:07:04","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=35826"},"modified":"2024-12-11T10:40:26","modified_gmt":"2024-12-11T16:40:26","slug":"resulta-un-muerto-y-un-herido-tras-segunda-explosion-en-salinas-victoria","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/resulta-un-muerto-y-un-herido-tras-segunda-explosion-en-salinas-victoria\/","title":{"rendered":"Resulta un muerto y un herido tras segunda explosi\u00f3n en Salinas Victoria"},"content":{"rendered":"<p>Salinas Victoria, N.L.- Un hombre muerto y otro herido fue el resultado de una segunda explosi\u00f3n del choque del tren que embisti\u00f3 una pipa cargada con combustible en la carretera Colombia, ubicada en Salinas Victoria, Nuevo Le\u00f3n.<br \/>\nSeg\u00fan trascendi\u00f3 a la pipa le falt\u00f3 enfriar y tuvo una ranura, la cual se abri\u00f3 de nuevo y tuvo un flamazo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-35828\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/12\/ac6089aa-ed94-4ec6-9249-4bc67482a149-300x201.jpeg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/12\/ac6089aa-ed94-4ec6-9249-4bc67482a149-300x201.jpeg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/12\/ac6089aa-ed94-4ec6-9249-4bc67482a149-768x515.jpeg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/12\/ac6089aa-ed94-4ec6-9249-4bc67482a149.jpeg 892w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\nTras esta explosi\u00f3n el hombre identificado como Carlos Puga fue llevado a la Clinica #6 con el 95% del cuerpo calcinado, perdiendo la vida horas mas tarde en el quirofano del nosocomio, mientras que otro hombre identificado como Carlos Ruiz, result\u00f3 lesionado y pas\u00f3 con quemaduras al Hospital Universitario pero no se especific\u00f3 en cuanto porcentaje de su cuerpo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-35829\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/12\/355a2670-0c78-4f32-9b32-423d8d4df46c-300x146.jpeg\" alt=\"\" width=\"300\" height=\"146\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/12\/355a2670-0c78-4f32-9b32-423d8d4df46c-300x146.jpeg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/12\/355a2670-0c78-4f32-9b32-423d8d4df46c-768x374.jpeg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2022\/12\/355a2670-0c78-4f32-9b32-423d8d4df46c.jpeg 888w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salinas Victoria, N.L.- Un hombre muerto y otro herido fue el resultado de una segunda explosi\u00f3n del choque del tren que embisti\u00f3 una pipa cargada con combustible en la carretera Colombia, ubicada en Salinas Victoria, Nuevo Le\u00f3n. Seg\u00fan trascendi\u00f3 a la pipa le falt\u00f3 enfriar y tuvo una ranura, la cual se abri\u00f3 de nuevo [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":35827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[1254],"class_list":["post-35826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-incendio"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/35826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=35826"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/35826\/revisions"}],"predecessor-version":[{"id":79973,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/35826\/revisions\/79973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/35827"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=35826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=35826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=35826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}