                       {"id":3650,"date":"2018-09-18T14:36:15","date_gmt":"2018-09-18T14:36:15","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=3650"},"modified":"2024-12-11T08:37:30","modified_gmt":"2024-12-11T14:37:30","slug":"hombre-balea-a-su-vecino-tras-discusion","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/hombre-balea-a-su-vecino-tras-discusion\/","title":{"rendered":"Hombre balea a su vecino tras discusi\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3651 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2018\/09\/whatsapp_image_2018-09-16_at_5.20.41_pm_2-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" \/>JU\u00c1REZ, N. L.- Un hombre result\u00f3 herido por una esquirla de arma de fuego, la ma\u00f1ana de este domingo en el municipio de Ju\u00e1rez.<\/p>\n<p style=\"text-align: justify;\">El hecho fue reportado sobre la calle Manzanares, en la colonia Los Huertos, cuando dos vecinos se encontraban ingiriendo bebidas alcoh\u00f3licas y repentinamente sostuvieron una pelea con otro habitante de la misma cuadra.<\/p>\n<p style=\"text-align: justify;\">Tras la pelea, uno de los hombres sac\u00f3 el arma de fuego y lesion\u00f3 a Cesar N. de 45 a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Tras la agresi\u00f3n, el presunto responsable, identificado solamente como Enrique, huy\u00f3 del lugar a bordo de un auto Jetta.<\/p>\n<p style=\"text-align: justify;\">Hasta el punto arribaron las autoridades, quienes localizaron un casquillo percutido calibre .45 mil\u00edmetros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JU\u00c1REZ, N. L.- Un hombre result\u00f3 herido por una esquirla de arma de fuego, la ma\u00f1ana de este domingo en el municipio de Ju\u00e1rez. El hecho fue reportado sobre la calle Manzanares, en la colonia Los Huertos, cuando dos vecinos se encontraban ingiriendo bebidas alcoh\u00f3licas y repentinamente sostuvieron una pelea con otro habitante de la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":3651,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[267,632],"class_list":["post-3650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-baleado","tag-colonia-los-huertos"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/3650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=3650"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/3650\/revisions"}],"predecessor-version":[{"id":64967,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/3650\/revisions\/64967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=3650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=3650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=3650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}