                       {"id":37030,"date":"2023-02-05T15:56:09","date_gmt":"2023-02-05T21:56:09","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=37030"},"modified":"2024-12-11T10:40:36","modified_gmt":"2024-12-11T16:40:36","slug":"cae-presunto-ladron-en-san-miguelito","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/cae-presunto-ladron-en-san-miguelito\/","title":{"rendered":"Cae presunto ladr\u00f3n en San Miguelito"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.- Cerca de las 13:00 horas del pasado jueves elementos de la Secretar\u00eda de Seguridad P\u00fablica Municipal de Ju\u00e1rez, detuvieron a un hombre en la colonia San Miguelito de dicha ciudad por un presunto robo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-37032\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/02\/IMG-20230205-WA0003-300x135.jpg\" alt=\"\" width=\"300\" height=\"135\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/02\/IMG-20230205-WA0003-300x135.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/02\/IMG-20230205-WA0003-1024x460.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/02\/IMG-20230205-WA0003-768x345.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/02\/IMG-20230205-WA0003-1536x690.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/02\/IMG-20230205-WA0003.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Todo sucedi\u00f3 cuando los efectivos se encontraban realizando recorridos de prevenci\u00f3n y vigilancia sobre la avenida Pablo Livas en su cruce con la calle Santa Ana de la colonia ya mencionada y observaron sobre la v\u00eda p\u00fablica un ecotaxi, el cual era manejado de una manera errada, por lo que inmediatamente le marcaron el alto a quien lo conducia.<\/p>\n<p>Al detener su marcha el veh\u00edculo tipo Versa, en color blanco con amarillo, descendi\u00f3 un hombre quien inmediatamente comenz\u00f3 a correr intentando huir del lugar, siendo alcanzado metros m\u00e1s adelante por los oficiales de polic\u00eda.<\/p>\n<p>El investigado se identific\u00f3 como Miguel R. de 20 a\u00f1os de edad; quien adopt\u00f3 una actitud agresiva en contra de los oficiales, por lo que tuvo que ser controlado por los mismos, quienes comenzaron con sus indagatorias en el sitio.<\/p>\n<p>Por su parte el conductor del autom\u00f3vil inform\u00f3 a los elementos de Polic\u00eda que hab\u00eda sido v\u00edctima de un robo por parte del hombre que estaba presente en el lugar, mismo quien lo amag\u00f3 con un cuchillo con mango en color rojo, logrando despojarlo de efectivo.<\/p>\n<p>Tras lo que le realizaron una inspecci\u00f3n f\u00edsica al detenido le localizaron la cantidad de $670.00 (00\/100 M.N.) y un cuchillo de aproximadamente 25 cm, con mango en color rojo.<\/p>\n<p>El ahora detenido fue trasladado de inmediato junto con el arma ante la autoridad competente para que responda por el delito de robo ejecutado con violencia y los que le resulten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Cerca de las 13:00 horas del pasado jueves elementos de la Secretar\u00eda de Seguridad P\u00fablica Municipal de Ju\u00e1rez, detuvieron a un hombre en la colonia San Miguelito de dicha ciudad por un presunto robo. &nbsp; &nbsp; Todo sucedi\u00f3 cuando los efectivos se encontraban realizando recorridos de prevenci\u00f3n y vigilancia sobre la avenida Pablo [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":37031,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,10],"tags":[3590,5962,5859],"class_list":["post-37030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad-juarez","tag-juarez-nl","tag-presunto-ladron","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/37030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=37030"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/37030\/revisions"}],"predecessor-version":[{"id":80593,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/37030\/revisions\/80593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/37031"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=37030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=37030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=37030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}