                       {"id":38148,"date":"2023-03-03T00:20:15","date_gmt":"2023-03-03T06:20:15","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=38148"},"modified":"2024-12-11T10:41:35","modified_gmt":"2024-12-11T16:41:35","slug":"rafaguean-domicilio-en-san-antonio-en-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/rafaguean-domicilio-en-san-antonio-en-juarez\/","title":{"rendered":"Rafaguean domicilio en San Antonio en Ju\u00e1rez"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.-Tremendo susto que se llevaron habitantes de la colonia San Antonio en el municipio de Ju\u00e1rez, tras escuchar alrededor de 30 detonaciones de arma de fuego que realizaron hac\u00eda un domicilio.<\/p>\n<p>El ataque se registr\u00f3 en la calle San Ignacio en la mencionada colonia.<\/p>\n<p>Presuntamente un hombre encapuchado en una motocicleta con un arma larga intentaba ejecutar a una mujer la cual logr\u00f3 resguardarse al interior del domicilio, resultando ilesa en el ataque.<\/p>\n<p>Sobre la calle quedaron los casquillos percutidos aparentemente de arma larga, autoridades arribaron al sitio para iniciar las investigaciones correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.-Tremendo susto que se llevaron habitantes de la colonia San Antonio en el municipio de Ju\u00e1rez, tras escuchar alrededor de 30 detonaciones de arma de fuego que realizaron hac\u00eda un domicilio. El ataque se registr\u00f3 en la calle San Ignacio en la mencionada colonia. Presuntamente un hombre encapuchado en una motocicleta con un arma [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":38149,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[4346],"class_list":["post-38148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-armas"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/38148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=38148"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/38148\/revisions"}],"predecessor-version":[{"id":81200,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/38148\/revisions\/81200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/38149"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=38148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=38148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=38148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}