                       {"id":4114,"date":"2018-10-11T22:05:39","date_gmt":"2018-10-11T22:05:39","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=4114"},"modified":"2024-12-11T08:53:18","modified_gmt":"2024-12-11T14:53:18","slug":"juanita-buendia-dice-adios-a-su-liderazgo-sindical","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/juanita-buendia-dice-adios-a-su-liderazgo-sindical\/","title":{"rendered":"Juanita Buend\u00eda: Dice adi\u00f3s a su liderazgo sindical"},"content":{"rendered":"<p style=\"text-align: justify;\">*Despu\u00e9s de 31 a\u00f1os de luchar por los trabajadores, la reconocida dirigente ahora lucha por su vida.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4115 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2018\/10\/DSCN0850-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/>CADEREYTA JIM\u00c9NEZ, N.L.-<br \/>\nA pocos d\u00edas de cortar sus 31 a\u00f1os como l\u00edder sindical del gremio de bur\u00f3cratas, Juanita Buend\u00eda Morales, respira hondo y su mirada adquiere un brillo de nostalgia.<br \/>\nLa dirigente sindical rememora que entr\u00f3 a laborar como secretaria en 1981, en la Secretar\u00eda del Ayuntamiento, cuando era alcalde Am\u00e9rico Montemayor y seis a\u00f1os despu\u00e9s, la vida le entrega la oportunidad de servir como l\u00edder de los bur\u00f3cratas en el a\u00f1o de 1987, despu\u00e9s de dos secretarios generales: Ra\u00fal Ortiz Huerta el fundador y Arturo L\u00f3pez Silva.<br \/>\n\u00bfAlguna an\u00e9cdota que la haya marcado?<br \/>\n\u201cEl paro de labores de tres d\u00edas que hicimos en el a\u00f1o 1989 con don Juan Ram\u00edrez Viera, porque no llegamos a un acuerdo con el contrato colectivo de trabajo e hicimos un paro de tres d\u00edas\u201d, recuerda la dirigente de 67 a\u00f1os de edad.<br \/>\nDesde entonces no han sido necesarias las medidas de presi\u00f3n, ya que se ha sabido conciliar por el bien de los trabajadores y el respeto a sus derechos.<br \/>\n\u00bfA sus 31 a\u00f1os de l\u00edder como define la palabra \u201cLiderazgo\u201d?<br \/>\n\u201cPues trabajo y m\u00e1s trabajo, porque aqu\u00ed la situaci\u00f3n es siempre gestionar, solicitar, pedir, resolver situaciones obviamente de los trabajadores, las necesidades m\u00e1s apremiantes; la soluci\u00f3n de problemas como cuando hay injusticias\u201d, se\u00f1al\u00f3.<br \/>\n\u00bfAlguna cosa que usted le haya gustado hacer y por alguna causa no pudo?<br \/>\n\u201cMe hubiera gustado hacer de coraz\u00f3n dos cosas: la m\u00e1s apremiante, abatir el rezago educativo de los trabajadores y la otra es una posada vacacional para los trabajadores muy necesaria para el descanso de ellos\u201d, se\u00f1al\u00f3 la dirigente en cuya gesti\u00f3n se construyeron las instalaciones del Sindicato \u00danico de Trabajadores al Servicio del Municipio de Cadereyta.<br \/>\nRelat\u00f3 la dirigente que ten\u00edan s\u00f3lo el terreno, pero con la ayuda de los trabajadores, actividades como rifas, bailes y el apoyo de las autoridades municipales, se pudo construir el edificio sindical.<br \/>\n\u00bfCu\u00e1l fue el alcalde m\u00e1s amigo del sindicato, que los apoy\u00f3 m\u00e1s?<br \/>\n\u201cDe alguna manera Valent\u00edn Tamez fue uno de ellos, pero fueron muchos. No todos por igual, pero si tenemos el apoyo de todos\u201d, dice con seguridad en su voz.<br \/>\nAl hablar de su adi\u00f3s como dirigente, Juanito Buend\u00eda el tono de su voz se hace m\u00e1s grave y dice sentir nostalgia y tristeza, ya que la cuesti\u00f3n sindical es su pasi\u00f3n, es su vida, aclara.<br \/>\n\u00bfEn su vida cu\u00e1l es la lucha m\u00e1s fuerte que ha tenido?<br \/>\n\u201cLa lucha que estoy haciendo ahorita contra el c\u00e1ncer, que me impulsa a retirarme\u201d, responde, mientras sus ojos se llenan de l\u00e1grimas, que no alcanzan a caer sobre el rostro de la menudita dirigente que sin duda pasa a la historia del sindicato por sus logros, sinsabores y luchas.<br \/>\nEl pron\u00f3stico es bueno, Juanita Buend\u00eda advierte que super\u00f3 toda la etapa de las quimioterapias, radiaciones y solo est\u00e1 a la espera de los resultados, sin embargo su semblante se ve sereno y su corto pelo es el sello de una lucha contra ese mal, al que piensa vencer.<br \/>\nAl retirarse, la dirigente sue\u00f1a con aprender a tocar piano, pintar, que es su pasi\u00f3n y muchas cosas m\u00e1s, que no ha podido hacer por el intenso trabajo para defender a sus compa\u00f1eros.<br \/>\nAgrega que ser\u00e1 la licenciada Norma Aracely Arizpe Su\u00e1rez, quien concluir\u00e1 los dos a\u00f1os que restan a su per\u00edodo este d\u00eda 31 de octubre donde habr\u00e1 un evento oficial, donde la dirigente dejar\u00e1 su cargo y tomar\u00e1 la protesta a quien en estos momentos es la representante en el Tribunal de Arbitraje.<br \/>\n\u00bfQu\u00e9 consejo le dar\u00eda a la nueva dirigente?<br \/>\n\u201cLe aconsejar\u00eda que cuide a los trabajadores, que trate siempre de mantener la armon\u00eda y la unidad sindical, porque es determinante en una organizaci\u00f3n, Yo creo que a nosotros nos mantuvo precisamente eso 31 a\u00f1os en el liderazgo\u201d, mencion\u00f3 por \u00faltimo la l\u00edder de 239 agremiados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Despu\u00e9s de 31 a\u00f1os de luchar por los trabajadores, la reconocida dirigente ahora lucha por su vida. CADEREYTA JIM\u00c9NEZ, N.L.- A pocos d\u00edas de cortar sus 31 a\u00f1os como l\u00edder sindical del gremio de bur\u00f3cratas, Juanita Buend\u00eda Morales, respira hondo y su mirada adquiere un brillo de nostalgia. La dirigente sindical rememora que entr\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4116,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[1354,2147],"class_list":["post-4114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-juanita-buendia","tag-sindicato-de-burocratas-municipales-de-cadereyta"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=4114"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4114\/revisions"}],"predecessor-version":[{"id":65224,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4114\/revisions\/65224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=4114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=4114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=4114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}