                       {"id":41238,"date":"2023-05-16T15:30:44","date_gmt":"2023-05-16T21:30:44","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=41238"},"modified":"2024-12-11T10:43:51","modified_gmt":"2024-12-11T16:43:51","slug":"realizan-labores-de-limpieza-en-alcantarillas-y-calles-en-cadereyta","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/realizan-labores-de-limpieza-en-alcantarillas-y-calles-en-cadereyta\/","title":{"rendered":"Realizan labores de limpieza en alcantarillas y calles en Cadereyta\u00a0"},"content":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- Tras las intensas lluvias que se registraron durante las \u00faltimas horas en Cadereyta, personal de Parques y Jardines y Servicios P\u00fablicos realizaron labores de limpieza de alcantarillas y algunas calles que presentaron acumulaciones de basura.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-41241\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0056-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0056-300x225.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0056-1024x768.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0056-768x576.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0056.jpg 1040w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Las cuadrillas municipales recorrieron calles del centro de la ciudad as\u00ed como de algunas colonias entre ellas Fomerrey Cadereyta y Valle de los Encinos, para liberar los registros pluviales y permitir el libre paso del agua en caso de que se presenten precipitaciones como est\u00e1 pronosticado para estos d\u00edas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-41243\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0061-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0061-300x225.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0061-1024x769.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0061-768x576.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0061-1536x1153.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230516-WA0061.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Tambi\u00e9n otro grupo de empleados con maquinaria y herramientas, retiraron basura, piedras y otro tipo objetos que el agua arrastr\u00f3 y dej\u00f3 en medio de algunas vialidades.<\/p>\n<p>Cosme Leal Cant\u00fa, alcalde de Cadereyta, se\u00f1al\u00f3 que los trabajos se realizan en todo el municipio, pues muchas alcantarillas fueron reportadas por la ciudadan\u00eda debido a que se encontraban tapadas y esto causa encharcamientos.<\/p>\n<p>\u201cLa gente hizo el llamado a nuestro Centro Integral de Atenci\u00f3n e inmediatamente acudimos a atenderlo, pues todos sabemos que si est\u00e1n tapadas las alcantarillas pues obviamente el agua no corre y esto nos causa serios problemas de encharcamientos e inundaciones a todos\u201d, dijo el Alcalde de Cadereyta.<\/p>\n<p>El presidente municipal exhort\u00f3 a la ciudadan\u00eda a extremar precauciones en caso de lluvia fuerte, no salir si no es estrictamente necesario, tener a la mano los n\u00fameros de emergencia y sobre todo, no arrojar basura a la calle para evitar que los registros pluviales se tapen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- Tras las intensas lluvias que se registraron durante las \u00faltimas horas en Cadereyta, personal de Parques y Jardines y Servicios P\u00fablicos realizaron labores de limpieza de alcantarillas y algunas calles que presentaron acumulaciones de basura. &nbsp; &nbsp; &nbsp; Las cuadrillas municipales recorrieron calles del centro de la ciudad as\u00ed como de algunas [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":41239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[7291,3840,7290,5859],"class_list":["post-41238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-alcantarillas","tag-cadereyta-jimenez-nl","tag-realizan-labores-de-limpieza","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=41238"}],"version-history":[{"count":4,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41238\/revisions"}],"predecessor-version":[{"id":82645,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41238\/revisions\/82645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/41239"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=41238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=41238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=41238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}