                       {"id":41340,"date":"2023-05-17T18:43:19","date_gmt":"2023-05-18T00:43:19","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=41340"},"modified":"2024-12-11T10:43:52","modified_gmt":"2024-12-11T16:43:52","slug":"trasplanta-umae-no-34-del-imss-un-corazon-para-dar-esperanza-de-vida-a-mujer-de-44-anos","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/trasplanta-umae-no-34-del-imss-un-corazon-para-dar-esperanza-de-vida-a-mujer-de-44-anos\/","title":{"rendered":"Trasplanta UMAE No. 34 del IMSS un coraz\u00f3n para dar esperanza de vida a mujer de 44 a\u00f1os"},"content":{"rendered":"<p>Monterrey, N L.- Una esperanza de vida lleg\u00f3 para una mujer de 44 a\u00f1os, cuando especialistas de la Unidad M\u00e9dica de Alta Especialidad (UMAE) Hospital de Cardiolog\u00eda No. 34 \u201cDr. Alfonso Trevi\u00f1o\u201d del Instituto Mexicano del Seguro Social (IMSS) en Nuevo Le\u00f3n le trasplantaron un nuevo coraz\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-41342\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230517-WA0072-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230517-WA0072-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230517-WA0072-1024x682.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230517-WA0072-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230517-WA0072-1536x1023.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/IMG-20230517-WA0072.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>La paciente, originaria de Saltillo, Coahuila, ingres\u00f3 a lista de espera el 28 de marzo de este a\u00f1o, con un diagn\u00f3stico de miocarditis (inflamaci\u00f3n del m\u00fasculo cardiaco) que limitaba la funci\u00f3n de su coraz\u00f3n a una tercera parte, inform\u00f3 el director de la UMAE No. 34, doctor Guillermo Sahag\u00fan S\u00e1nchez.<\/p>\n<p>El trasplante fue posible gracias a la donaci\u00f3n altruista de un joven de 23 a\u00f1os, quien desafortunadamente falleci\u00f3 a causa de una hemorragia cerebral derivada de una malformaci\u00f3n arteriovenosa.<\/p>\n<p>El equipo m\u00e9dico del Hospital de Cardiolog\u00eda No. 34 acudi\u00f3 a procurar el coraz\u00f3n a la UMAE Hospital de Especialidades del Centro M\u00e9dico Nacional (CMN) Siglo XXI del IMSS en la Ciudad de M\u00e9xico.<\/p>\n<p>Una vez extra\u00eddo el \u00f3rgano, el equipo del Hospital de Cardiolog\u00eda No. 34 vol\u00f3 desde Toluca al Aeropuerto Internacional de Monterrey \u201cGeneral Mariano Escobedo\u201d, donde un helic\u00f3ptero de Protecci\u00f3n Civil de Nuevo Le\u00f3n ya los esperaba para trasladarlos a la unidad m\u00e9dica, ubicada en la avenida Abraham Lincoln, en Monterrey.<\/p>\n<p>Ya en el quir\u00f3fano, la cirug\u00eda de trasplante fue exitosa, la cual dur\u00f3 aproximadamente cinco horas, con la participaci\u00f3n de cirujanos cardiovasculares, anestesi\u00f3logos, enfermeras quir\u00fargicas y circulantes, entre otros integrantes del equipo de salud.<\/p>\n<p>Este proceso quir\u00fargico fue el segundo de su tipo en la unidad en lo que va del 2023 y el n\u00famero 87 desde 1997, cuando inici\u00f3 el programa.<\/p>\n<p>Un donador voluntario de \u00f3rganos y tejidos puede consultar la p\u00e1gina del Centro Nacional de Trasplantes: https:\/\/www.gob.mx\/cenatra\/ o visitar la p\u00e1gina del IMSS http:\/\/www.imss.gob.mx\/salud-en-linea\/donacion-organos donde podr\u00e1n registrarse como donadores voluntarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey, N L.- Una esperanza de vida lleg\u00f3 para una mujer de 44 a\u00f1os, cuando especialistas de la Unidad M\u00e9dica de Alta Especialidad (UMAE) Hospital de Cardiolog\u00eda No. 34 \u201cDr. Alfonso Trevi\u00f1o\u201d del Instituto Mexicano del Seguro Social (IMSS) en Nuevo Le\u00f3n le trasplantaron un nuevo coraz\u00f3n. &nbsp; &nbsp; &nbsp; &nbsp; La paciente, originaria de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":41341,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[1249,7344,5859],"class_list":["post-41340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-imss","tag-transplante-de-corazon","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=41340"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41340\/revisions"}],"predecessor-version":[{"id":82703,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41340\/revisions\/82703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/41341"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=41340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=41340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=41340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}