                       {"id":41530,"date":"2023-05-22T18:06:34","date_gmt":"2023-05-23T00:06:34","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=41530"},"modified":"2024-12-11T10:43:54","modified_gmt":"2024-12-11T16:43:54","slug":"amarran-y-encintan-a-presunto-ladron","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/amarran-y-encintan-a-presunto-ladron\/","title":{"rendered":"Amarran y encintan a presunto ladr\u00f3n"},"content":{"rendered":"\n<p>Ju\u00e1rez, N.L.- Un presunto ladr\u00f3n fue golpeado, amarrado y encintado en un poste de la colonia Mirador del Parque en el municipio de Ju\u00e1rez.<br>Autoridades recibieron el reporte la tarde del domingo en la calle Tamarindo en su cruce con Olivo, donde elementos de la Polic\u00eda Municipal arribaron y encontraron al hombre de aproximadamente 25 a\u00f1os de edad, desnudo, con lesiones de golpes, maniatado y encintado en un poste, con un cartel en el pecho que dec\u00eda: &#8220;Esto le va a pasar a todos los ratas&#8221;.<br>Presuntamente se tratar\u00eda de un ajuste de cuentas, ya que seg\u00fan testigos fue dejado en el lugar por hombres abordo de un veh\u00edculo y no como en otras ocasiones que los vecinos hacen justicia por su propia mano y detienen al presunto ladr\u00f3n.<br>En el lugar se di\u00f3 la movilizaci\u00f3n de personal de Servicios Periciales para recabar evidencia que ayude a la investigaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/picsart_23-05-22_17-22-00-8684765845043731187260-300x195.jpg\" alt=\"\" class=\"wp-image-41529\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/picsart_23-05-22_17-22-00-8684765845043731187260-300x195.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/05\/picsart_23-05-22_17-22-00-8684765845043731187260.jpg 512w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\r\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Un presunto ladr\u00f3n fue golpeado, amarrado y encintado en un poste de la colonia Mirador del Parque en el municipio de Ju\u00e1rez.Autoridades recibieron el reporte la tarde del domingo en la calle Tamarindo en su cruce con Olivo, donde elementos de la Polic\u00eda Municipal arribaron y encontraron al hombre de aproximadamente 25 a\u00f1os [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":41528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[7428,7429,5366,7427,3923],"class_list":["post-41530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-encintado","tag-iscp","tag-ladron","tag-maniatado","tag-policia-municipal"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=41530"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41530\/revisions"}],"predecessor-version":[{"id":82805,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41530\/revisions\/82805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/41528"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=41530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=41530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=41530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}