                       {"id":41717,"date":"2023-05-26T15:13:49","date_gmt":"2023-05-26T21:13:49","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=41717"},"modified":"2024-12-11T10:43:56","modified_gmt":"2024-12-11T16:43:56","slug":"valida-la-corte-que-militares-esten-en-tareas-de-seguridad-publica","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/valida-la-corte-que-militares-esten-en-tareas-de-seguridad-publica\/","title":{"rendered":"Valida la Corte que militares est\u00e9n en tareas de seguridad p\u00fablica"},"content":{"rendered":"<p>CDMX.- El acuerdo presidencial que autoriz\u00f3 el despliegue de las fuerzas armadas en tareas de seguridad p\u00fablica fue validado por la Suprema Corte de Justicia de la Naci\u00f3n (SCJN), al determinar que esta disposici\u00f3n no invade las atribuciones de los gobierno estatales ni municipales.<\/p>\n<p>Por mayor\u00eda de siete votos, el pleno de ministros resolvi\u00f3 as\u00ed las controversias constitucionales 85, 87 y 91\/2020, promovidas respectivamente por Colima, Michoac\u00e1n y el ayuntamiento de Pabell\u00f3n de Arteaga, Aguascalientes, en contra del acuerdo presidencial promulgado el 11 de mayo de 2020.<\/p>\n<p>En noviembre del a\u00f1o pasado, la SCJN resolvi\u00f3 en t\u00e9rminos parecidos otra impugnaci\u00f3n al mismo acuerdo presidencial, que tambi\u00e9n fue desechada, debido a que no se comprob\u00f3 que el Ejecutivo haya invadido las facultades del Legislativo.<\/p>\n<p>La ministra Ana Margarita R\u00edos Farjat, quien fue la ponente en el asunto actual, expres\u00f3 que la Secretar\u00eda de la Defensa Nacional (Sedena) tiene un papel trascendental en el proceso de maduraci\u00f3n y profesionalizaci\u00f3n de la Guardia Nacional como un cuerpo de seguridad p\u00fablica.<\/p>\n<p>Agreg\u00f3 que al resolver las controversias, la Corte propone de nuevo reconocer la constitucionalidad de parte de esta coordinaci\u00f3n entre las secretar\u00edas de Seguridad y Protecci\u00f3n Ciudadana con las de la Defensa Nacional y de Marina.<\/p>\n<p>Opin\u00f3 que la consolidaci\u00f3n de la Guardia Nacional es una tarea conjunta de diversas dependencias federales y la Corte s\u00f3lo ha delimitado la manera en que pueden organizarse, sin que esto modifique las condiciones de los integrantes de las fuerzas militares.<\/p>\n<p>Se\u00f1al\u00f3 que el acto impugnado no es una norma general que aplique a todos los \u00f3rdenes de gobierno, sino que legalmente es un acuerdo, que s\u00f3lo tiene jurisdicci\u00f3n sobre los \u00f3rganos dependientes del Poder Ejecutivo, por lo cual sus efectos no inciden en la esfera jur\u00eddica de los gobiernos locales.<\/p>\n<p>La ministra Loretta Ortiz Ahlf coincidi\u00f3 en este punto y dijo que no se desvirt\u00faa la coordinaci\u00f3n en materia de seguridad p\u00fablica, ni se someten a la Federaci\u00f3n las facultades de los municipios o estados.<\/p>\n<p>FUENTE : LA JORNADA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CDMX.- El acuerdo presidencial que autoriz\u00f3 el despliegue de las fuerzas armadas en tareas de seguridad p\u00fablica fue validado por la Suprema Corte de Justicia de la Naci\u00f3n (SCJN), al determinar que esta disposici\u00f3n no invade las atribuciones de los gobierno estatales ni municipales. Por mayor\u00eda de siete votos, el pleno de ministros resolvi\u00f3 as\u00ed [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":41718,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[7501,5025,7502,2085,5859],"class_list":["post-41717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-constitucionalidad","tag-guardianacional","tag-militantesenactividadesdeseguridadpublica","tag-scjn","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=41717"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41717\/revisions"}],"predecessor-version":[{"id":82907,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/41717\/revisions\/82907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/41718"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=41717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=41717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=41717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}