                       {"id":43018,"date":"2023-06-27T15:07:44","date_gmt":"2023-06-27T21:07:44","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=43018"},"modified":"2024-12-11T10:44:11","modified_gmt":"2024-12-11T16:44:11","slug":"continua-combate-aereo-contra-incendio-en-el-pajonal","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/continua-combate-aereo-contra-incendio-en-el-pajonal\/","title":{"rendered":"Contin\u00faa combate a\u00e9reo contra incendio en El Pajonal"},"content":{"rendered":"<p>Santa Catarina, N.L.- Con el objetivo de seguir manteniendo control sobre el incendio en El Pajonal, del municipio de Santa Catarina, Protecci\u00f3n Civil Nuevo Le\u00f3n informa que en acciones para fortalecer el ataque a\u00e9reo hoy se suma un helic\u00f3ptero Mi-17 de la Guardia Nacional.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-43020\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0028-300x135.jpg\" alt=\"\" width=\"300\" height=\"135\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0028-300x135.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0028-1024x461.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0028-768x346.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0028-1536x691.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0028.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>El incendio se combate con dos helic\u00f3pteros de Protecci\u00f3n Civil; un Mi-17 de Secretaria de Marina y yn Mi-17 de la Guardia Nacional.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-43021\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0027-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0027-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0027-1024x683.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0027-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0027-1536x1024.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/06\/IMG-20230627-WA0027.jpg 1599w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>La fuerza de tarea es de 140 brigadistas de los tres \u00f3rganos de Gobierno.<\/p>\n<p>Trascendiendo que<\/p>\n<p>Las acciones estar\u00e1n enfocadas en trabajar en el sector bravo.<\/p>\n<p>El cual es el \u00fanico sector que presenta actividad en el Incidente.<\/p>\n<p>Asimismo, los rescatitas realizan brechas cortafuegos y ataque a\u00e9reo con aeronaves.<\/p>\n<p>No existe riesgo a la poblaci\u00f3n, ni comunidades cercanas y se continuar\u00e1 trabajando para aumentar el control del incidente.<\/p>\n<p>Hasta el momento se encuentran apoyando grupos como Brigada F\u00e9nix PCENL, Brigada Jaguares PC Santa Catarina, PC Monterrey, PC Ju\u00e1rez<\/p>\n<p>PC Guadalupe, Bomberos Guadalupe, CONAFOR, CONANP, Amigos de la Sierra, Sedena, Secretaria de Seguridad P\u00fablica, adem\u00e1s de pipa de abastecimiento de Agua y Drenaje, Pipa de agua de abastecimiento de Bomberos Guadalupe,<\/p>\n<p>Pipa de agua de Bomberos HG.<\/p>\n<p>Adem\u00e1s de dos helic\u00f3pteros de Protecci\u00f3n Civil Nuevo Le\u00f3n, un helic\u00f3ptero de la Guardia Nacional Mi-17 y otro<\/p>\n<p>de la Secretaria de Marina Mi-17.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santa Catarina, N.L.- Con el objetivo de seguir manteniendo control sobre el incendio en El Pajonal, del municipio de Santa Catarina, Protecci\u00f3n Civil Nuevo Le\u00f3n informa que en acciones para fortalecer el ataque a\u00e9reo hoy se suma un helic\u00f3ptero Mi-17 de la Guardia Nacional. &nbsp; &nbsp; &nbsp; &nbsp; El incendio se combate con dos helic\u00f3pteros [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":43019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[8055,8056,1254,5859],"class_list":["post-43018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-continua-combate-aereo","tag-el-pajonal","tag-incendio","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/43018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=43018"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/43018\/revisions"}],"predecessor-version":[{"id":83577,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/43018\/revisions\/83577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/43019"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=43018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=43018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=43018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}