                       {"id":43080,"date":"2023-06-28T15:54:39","date_gmt":"2023-06-28T21:54:39","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=43080"},"modified":"2024-12-11T10:44:12","modified_gmt":"2024-12-11T16:44:12","slug":"nino-cae-de-tirolesa-de-12-metros-en-nl-tras-romperse-arnes","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/nino-cae-de-tirolesa-de-12-metros-en-nl-tras-romperse-arnes\/","title":{"rendered":"Ni\u00f1o cae de tirolesa de 12 metros en NL tras romperse arn\u00e9s\u00a0"},"content":{"rendered":"<p>Monterrey, N.L.- Un ni\u00f1o cay\u00f3 de m\u00e1s de 10 metros de altura despu\u00e9s de que se rompiera el arn\u00e9s de una tirolesa ubicada en el Parque Fundidora en Nuevo Le\u00f3n.<\/p>\n<p>A trav\u00e9s de redes sociales se viraliz\u00f3 un video en el que se observa al ni\u00f1o aventarse de la tirolesa, seguido de un hombre, cada uno con su propio arn\u00e9s.<\/p>\n<p>Sin embargo, el impulso no fue suficiente y la velocidad de ambos comienza a disminuir conforme se desplazan por el cable hasta finalmente detenerse a la mitad.<\/p>\n<p>En el instante en que ambos se detienen, se ve al menor caer desde la tirolesa al suelo, desde una altura que algunos medios han afirmado podr\u00eda ser de hasta 12 metros.<\/p>\n<p>Mientras cae, se escucha a la mujer que graba gritar por el ni\u00f1o.<\/p>\n<p>Sin embargo, el menor cay\u00f3 hacia el lago que se encuentra en la Plaza de los Loros, que tendr\u00eda una profundidad de seis a siete metros.<\/p>\n<p>Los primeros reportes aseguran que fue rescatado al instante y no sufri\u00f3 lesiones por el impacto.<\/p>\n<p>FUENTE: ARISTEGUI NOTICIAS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey, N.L.- Un ni\u00f1o cay\u00f3 de m\u00e1s de 10 metros de altura despu\u00e9s de que se rompiera el arn\u00e9s de una tirolesa ubicada en el Parque Fundidora en Nuevo Le\u00f3n. A trav\u00e9s de redes sociales se viraliz\u00f3 un video en el que se observa al ni\u00f1o aventarse de la tirolesa, seguido de un hombre, cada [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":43081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[4196,8093,5113,8092,5859],"class_list":["post-43080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-accidente","tag-accidentenl","tag-nuevoleon","tag-parquefundidora","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/43080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=43080"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/43080\/revisions"}],"predecessor-version":[{"id":83611,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/43080\/revisions\/83611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/43081"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=43080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=43080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=43080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}