                       {"id":43150,"date":"2023-06-29T15:34:20","date_gmt":"2023-06-29T21:34:20","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=43150"},"modified":"2024-12-11T10:44:13","modified_gmt":"2024-12-11T16:44:13","slug":"asesinan-a-hipolito-mora-ex-lider-de-autodefensas-en-michoacan","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/asesinan-a-hipolito-mora-ex-lider-de-autodefensas-en-michoacan\/","title":{"rendered":"Asesinan a Hip\u00f3lito Mora, ex l\u00edder de autodefensas en Michoac\u00e1n"},"content":{"rendered":"<p>Morelia, Mich.- En la tenencia Felipe Carrillo Puerto, mejor conocida como la Ruana, municipio de Buenavista, este mediod\u00eda se registr\u00f3 una fuerte balacera y luego fue incendiada una camioneta blindada, al parecer propiedad del ex l\u00edder de las autodefensas, Hip\u00f3lito Mora Ch\u00e1vez.<\/p>\n<p>Se desconoce si dentro del veh\u00edculo se encontraba Mora Ch\u00e1vez.<\/p>\n<p>Vecinos del lugar de los hechos aseguraron que al menos hab\u00eda una persona dentro de la camioneta.<\/p>\n<p>Al momento no hay versi\u00f3n oficial y la versi\u00f3n no oficial es que minutos antes de las 12 horas se report\u00f3 que hombres armados interceptaron a Mora Ch\u00e1vez y a sus escoltas cerca del domicilio del ex l\u00edder de autodefensas. Tambi\u00e9n que se registr\u00f3 una balacera que dur\u00f3 varios minutos.<\/p>\n<p>Mora Ch\u00e1vez sobrevivi\u00f3 a dos atentados, uno el 26 de noviembre de 2022, y otro m\u00e1s el 4 de marzo del presente a\u00f1o, los dos en esta localidad de aproximadamente 18 mil habitantes.<\/p>\n<p>Cabe se\u00f1alar que desde que inici\u00f3 el levantamiento armado en contra del crimen organizado ha sido amenazado de muerte en varias ocasiones.<\/p>\n<p>La Fiscal\u00eda General del Estado inform\u00f3 que elementos de la dependencia estatal se trasladaron a la Ruana para saber de lo ocurrido de la agresi\u00f3n a Hip\u00f3lito Mora y sus escoltas.<\/p>\n<p>FUENTE: LA JORNADA<\/p>\n<p>Foto:grupo\u00a0 marmor<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morelia, Mich.- En la tenencia Felipe Carrillo Puerto, mejor conocida como la Ruana, municipio de Buenavista, este mediod\u00eda se registr\u00f3 una fuerte balacera y luego fue incendiada una camioneta blindada, al parecer propiedad del ex l\u00edder de las autodefensas, Hip\u00f3lito Mora Ch\u00e1vez. Se desconoce si dentro del veh\u00edculo se encontraba Mora Ch\u00e1vez. Vecinos del lugar [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":43152,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[4350,8120,8119,5859],"class_list":["post-43150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-asesinado","tag-autodefensasmorelia","tag-hipolitomora","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/43150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=43150"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/43150\/revisions"}],"predecessor-version":[{"id":83643,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/43150\/revisions\/83643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/43152"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=43150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=43150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=43150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}