                       {"id":4351,"date":"2018-10-25T23:05:27","date_gmt":"2018-10-25T23:05:27","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=4351"},"modified":"2024-12-11T08:53:20","modified_gmt":"2024-12-11T14:53:20","slug":"hallan-a-joven-desaparecido","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/hallan-a-joven-desaparecido\/","title":{"rendered":"Hallan a joven desaparecido"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4352 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2018\/11\/1-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" \/>A una semana de desaparecido, fue encontrado Jos\u00e9 Eduardo Barboza Hern\u00e1ndez, quien hab\u00eda sido visto por \u00faltima vez en casa de sus hermanos en la calle Castell\u00f3n de Plana en Praderas de San Juan.<br \/>\nLa familia report\u00f3 la desaparici\u00f3n en el CODE, Locatel y otras instituciones, pero nada se sab\u00eda de su paradero, haciendo crecer le inquietud de sus familiares, que tem\u00edan lo peor.<br \/>\nEl carbonero originario de Coahuila hab\u00eda sido visto muy extra\u00f1o, como ausente de lo que le rodeaba en los \u00faltimos d\u00edas, sin embargo no hab\u00eda externado nada a sus hermanos con quienes viv\u00eda temporalmente en esta ciudad de Ju\u00e1rez.<br \/>\nMojado y entumecido por el fr\u00edo, el joven de 27 a\u00f1os, fue encontrado caminando por unas v\u00edas del ferrocarril en Sabinas, Coahuila el mi\u00e9rcoles por la ma\u00f1ana.<br \/>\nAun no se detalla del porqu\u00e9 de su desaparici\u00f3n, si fue voluntaria o forzada, debido a que la familia que se encontraba angustiada, velaba por su salud.<br \/>\nSe cree que Jos\u00e9 Eduardo, quien no padece facultades mentales, en un lapsus de memoria, se fue caminando hasta su ciudad natal en la regi\u00f3n carbon\u00edfera de Coahuila, sin saberse motivos, ya que los hermanos con quienes conviv\u00eda en Ju\u00e1rez, Nuevo Le\u00f3n, lo trataban bien y buscaban de \u00e9l una rehabilitaci\u00f3n.<br \/>\nEl joven fue entregado a su madre quien radica en aquella regi\u00f3n y as\u00ed acab\u00f3 la zozobra de toda su familia que se hab\u00eda volcado en su b\u00fasqueda, visitando demarcaciones de polic\u00edas, hospitales, y puestos de socorro, adem\u00e1s de pegar en los postes la fotograf\u00eda de Jos\u00e9 Eduardo Barboza Hern\u00e1ndez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A una semana de desaparecido, fue encontrado Jos\u00e9 Eduardo Barboza Hern\u00e1ndez, quien hab\u00eda sido visto por \u00faltima vez en casa de sus hermanos en la calle Castell\u00f3n de Plana en Praderas de San Juan. La familia report\u00f3 la desaparici\u00f3n en el CODE, Locatel y otras instituciones, pero nada se sab\u00eda de su paradero, haciendo crecer [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4352,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[1182],"class_list":["post-4351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-hallan-desaparecido"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=4351"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4351\/revisions"}],"predecessor-version":[{"id":65352,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4351\/revisions\/65352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=4351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=4351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=4351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}