                       {"id":44500,"date":"2023-08-01T09:53:10","date_gmt":"2023-08-01T15:53:10","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=44500"},"modified":"2023-08-01T09:53:10","modified_gmt":"2023-08-01T15:53:10","slug":"investigan-derrame-de-aceite-en-carretera-a-san-roque","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/investigan-derrame-de-aceite-en-carretera-a-san-roque\/","title":{"rendered":"Investigan derrame de aceite en Carretera a San Roque"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.-La tarde de ayer se registr\u00f3 un derrame de aceite sobre la carretera a San Roque a la altura de la avenida Rancho Viejo en el Municipio de Ju\u00e1rez.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-44502\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/08\/Picsart_23-08-01_09-52-45-318-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/08\/Picsart_23-08-01_09-52-45-318-300x225.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/08\/Picsart_23-08-01_09-52-45-318-1024x768.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/08\/Picsart_23-08-01_09-52-45-318-768x576.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/08\/Picsart_23-08-01_09-52-45-318.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Tras un reporte que se recibi\u00f3 alrededor de las 7:25 de la tarde por parte de motociclistas que circulaban por el lugar y quienes sufrieron el derrape de sus motocicletas en el sitio, arribaron elementos de Protecci\u00f3n Civil del Municipio a cargo del Director Francisco Moyar, quienes procedieron a aplicar bultos de polvo absorbente.<\/p>\n<p>En el lugar hicieron presencia Polic\u00edas de Fuerza Civil quienes apoyaron a los elementos de Protecci\u00f3n Civil y Tr\u00e1nsito del Municipio controlando el tr\u00e1fico para evitar aglomeraciones y accidentes.<\/p>\n<p>El derrame de aceite abarc\u00f3 alrededor de 500 metros e inici\u00f3 desde la avenida Rancho viejo.<\/p>\n<p>Hasta el momento, se desconoce quienes fueron los responsables del derrame.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.-La tarde de ayer se registr\u00f3 un derrame de aceite sobre la carretera a San Roque a la altura de la avenida Rancho Viejo en el Municipio de Ju\u00e1rez. &nbsp; &nbsp; &nbsp; &nbsp; Tras un reporte que se recibi\u00f3 alrededor de las 7:25 de la tarde por parte de motociclistas que circulaban por el [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":44501,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[8636,8635,3590,5859],"class_list":["post-44500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-carretera-san-roque","tag-investigan-derrame-de-aceite","tag-juarez-nl","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=44500"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44500\/revisions"}],"predecessor-version":[{"id":44503,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44500\/revisions\/44503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/44501"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=44500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=44500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=44500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}