                       {"id":44550,"date":"2023-08-01T19:17:27","date_gmt":"2023-08-02T01:17:27","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=44550"},"modified":"2023-08-01T19:17:33","modified_gmt":"2023-08-02T01:17:33","slug":"lo-detienen-por-infraccion-debia-secuestr0s","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/lo-detienen-por-infraccion-debia-secuestr0s\/","title":{"rendered":"Lo detienen por infracci\u00f3n; deb\u00eda secuestr0s"},"content":{"rendered":"\n<p>Ju\u00e1rez, N.L.- Polic\u00edas de Ju\u00e1rez detuvieron a un hombre que contaba con orden de aprehensi\u00f3n vigente por el Delito de Secuestro, en la colonia Villas de San Jos\u00e9.<br \/>Los hechos ocurrieron cerca de las 23:00 horas de este 31 de julio cuando efectivos municipales circulaban sobre la avenida Flor de Loto, cuando se percataron que un hombre a bordo de una camioneta en color negro manejaba de manera err\u00e1tica poniendo en peligro a las personas que circulaban por el lugar; por lo que inmediatamente procedieron a marcarle el alto a dicho conductor.<br \/>Al bajar de la unidad, los efectivos municipales se aproximaron al veh\u00edculo tipo pick up, del cual baj\u00f3 su conductor adoptando una actitud agresiva en contra de los uniformados, por lo que fue controlado por los elementos y se identific\u00f3 como Josu\u00e9 V. de 26 a\u00f1os de edad, quien fue detenido por faltas al reglamento c\u00edvico del Municipio de Ju\u00e1rez.<br \/>Sin embargo al comunicar su detenci\u00f3n por la central de radio, el C4 Municipal indic\u00f3 que el ahora detenido contaba con una orden de aprehensi\u00f3n vigente por el Delito de Secuestro, motivo por el cual la autoridad ministerial especializada en Aprehensiones fue alertada sobre su detenci\u00f3n y fueron quienes acudieron a las instalaciones de la Secretar\u00eda de Seguridad P\u00fablica Municipal de Ju\u00e1rez para realizar el traslado del ahora detenido ante la autoridad competente.<br \/>Trascendi\u00f3 que detenido ser\u00e1 investigado de manera conjunta por autoridades especializadas para descartar su participaci\u00f3n en diversos delitos de alto impacto cometidos en la zona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Polic\u00edas de Ju\u00e1rez detuvieron a un hombre que contaba con orden de aprehensi\u00f3n vigente por el Delito de Secuestro, en la colonia Villas de San Jos\u00e9.Los hechos ocurrieron cerca de las 23:00 horas de este 31 de julio cuando efectivos municipales circulaban sobre la avenida Flor de Loto, cuando se percataron que un [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":44549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[8659,819,4308],"class_list":["post-44550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-delito-por-secuestro","tag-detenido","tag-orden-de-aprehension"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=44550"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44550\/revisions"}],"predecessor-version":[{"id":44551,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44550\/revisions\/44551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/44549"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=44550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=44550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=44550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}