                       {"id":44618,"date":"2023-08-02T21:22:50","date_gmt":"2023-08-03T03:22:50","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=44618"},"modified":"2023-08-02T21:26:05","modified_gmt":"2023-08-03T03:26:05","slug":"apresan-a-dos-con-moto-robada","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/apresan-a-dos-con-moto-robada\/","title":{"rendered":"Apresan a dos con moto robada"},"content":{"rendered":"\n<p>Ju\u00e1rez,N.L.- La Polic\u00eda de Ju\u00e1rez detuvo a dos sujetos cuando circulaban a bordo de un veh\u00edculo con reporte de robo en la colonia Monte Kristal.<br \/>Los hechos se originaron cerca del mediod\u00eda de este 02 de agosto del 2023, cuando elementos de la polic\u00eda pertenecientes a la Secretar\u00eda de Seguridad P\u00fablica de Ju\u00e1rez, se encontraban realizando sus recorridos de prevenci\u00f3n y vigilancia sobre la avenida Monte Kristal en su cruce con la avenida Las Torres, en la colonia ya mencionada cuando observaron una motocicleta tripulada por dos hombres a exceso de velocidad, la cual no portaba placas de circulaci\u00f3n, motivo por el cual le marcaron el alto; sin embargo el conductor aceler\u00f3 su marcha desplaz\u00e1ndose algunos metros m\u00e1s, haciendo caso omiso a la indicaci\u00f3n de los oficiales.<br \/>Derivado de la acci\u00f3n evasiva que realiz\u00f3 el conductor se gener\u00f3 una persecuci\u00f3n que termin\u00f3 metros m\u00e1s adelante, en donde se logr\u00f3 detener a la motocicleta sobre la calle Monte Marfil, descendiendo de la motocicleta de marca Honda Cargo 150 en color Rojo con negro sus dos tripulantes, quienes adoptaron una actitud violenta y prepotente en contra de los polic\u00edas, neg\u00e1ndose a proporcionar dato alguno y tratando de escapar de los uniformados en repetidas ocasiones.<br \/>Al comenzar con sus labores de investigaci\u00f3n los oficiales solicitaron informaci\u00f3n al C4 Municipal apoy\u00e1ndose del n\u00famero de serie de la motocicleta, comunic\u00e1ndoles que dicho veh\u00edculo tenia reporte de robo en la colonia Hacienda San Jos\u00e9, en la misma ciudad<br \/>Ante tales hechos se procedi\u00f3 a detener a quien dijo llamarse \u00c1ngel G. de 38 a\u00f1os de edad y a Jos\u00e9 H. de 17, a quienes trasladaron ante la autoridad competente, junto con la motocicleta para que respondan por el delito equiparable al robo de veh\u00edculo y los que les resulten.<br \/>Trascendi\u00f3 entre las primeras investigaciones realizadas por las autoridades, que el detenido quien dijo llamarse \u00c1ngel G. de 38 a\u00f1os, en realidad se llama Jes\u00fas R. de 35 a\u00f1os y se encuentra siendo investigado por diversos delitos patrimoniales cometidos con violencia y por delitos cometidos en contra de la comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez,N.L.- La Polic\u00eda de Ju\u00e1rez detuvo a dos sujetos cuando circulaban a bordo de un veh\u00edculo con reporte de robo en la colonia Monte Kristal.Los hechos se originaron cerca del mediod\u00eda de este 02 de agosto del 2023, cuando elementos de la polic\u00eda pertenecientes a la Secretar\u00eda de Seguridad P\u00fablica de Ju\u00e1rez, se encontraban realizando [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":44617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[8672,8673,6026],"class_list":["post-44618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-2-detenidos","tag-delitos-cometidos","tag-sorprenden-con-moto-robada"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=44618"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44618\/revisions"}],"predecessor-version":[{"id":44619,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44618\/revisions\/44619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/44617"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=44618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=44618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=44618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}