                       {"id":44760,"date":"2023-08-06T22:43:29","date_gmt":"2023-08-07T04:43:29","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=44760"},"modified":"2023-08-06T22:46:11","modified_gmt":"2023-08-07T04:46:11","slug":"atracan-tienda-y-hieren-a-empleada","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/atracan-tienda-y-hieren-a-empleada\/","title":{"rendered":"Atracan tienda y hieren a empleada"},"content":{"rendered":"\n<p>Ju\u00e1rez, N.L.- Un asaltante, acompa\u00f1ado por un taxista, arrib\u00f3 a un negocio en la colonia Hacienda La Escondida, donde con un arma blanca hiri\u00f3 a la dependienta del lugar, llev\u00e1ndose unos tel\u00e9fonos celulares.<br \/>Los hechos ocurrieron este domingo a las 6:35 de la tarde, cuando baj\u00f3 de un taxi blanco y amarillo un sujeto de unos 38 a\u00f1os y de 1.70 metros de estatura, vestido de pantal\u00f3n azul, playera blanca y gorra negra, quien entr\u00f3 a la tienda de abarrotes situada en la calle Quinta Naranjo.<br \/>En forma violenta, el desconocido se abalanz\u00f3 contra la despachadora y la hiri\u00f3 en una mano , mientras hu\u00eda con varios celulares que se encontraban en el lugar.<br \/>El desconocido abord\u00f3 el taxi con su c\u00f3mplice para huir con rumbo desconocido.<br \/>Cabe mencionar que es la tercera vez que es asaltado en forma violenta este negocio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Un asaltante, acompa\u00f1ado por un taxista, arrib\u00f3 a un negocio en la colonia Hacienda La Escondida, donde con un arma blanca hiri\u00f3 a la dependienta del lugar, llev\u00e1ndose unos tel\u00e9fonos celulares.Los hechos ocurrieron este domingo a las 6:35 de la tarde, cuando baj\u00f3 de un taxi blanco y amarillo un sujeto de unos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":44759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[8721,4404,8723,8722],"class_list":["post-44760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-asaltan-tienda","tag-camara-de-seguridad","tag-companado-por-un-taxis","tag-hieren-a-la-empleada"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=44760"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44760\/revisions"}],"predecessor-version":[{"id":44761,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44760\/revisions\/44761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/44759"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=44760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=44760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=44760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}