                       {"id":44998,"date":"2023-08-11T00:52:40","date_gmt":"2023-08-11T06:52:40","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=44998"},"modified":"2023-08-11T00:52:43","modified_gmt":"2023-08-11T06:52:43","slug":"cumple-paco-trevino-mejoras-en-fuentes-de-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/cumple-paco-trevino-mejoras-en-fuentes-de-juarez\/","title":{"rendered":"Cumple Paco Trevi\u00f1o mejoras en Fuentes de Ju\u00e1rez"},"content":{"rendered":"\n<p>Ju\u00e1rez, N.L.- En beneficio de miles de habitantes de la Colonia Fuentes de Ju\u00e1rez y sectores aleda\u00f1os, el Municipio de Ju\u00e1rez inici\u00f3 obras de repavimentaci\u00f3n y ampliaci\u00f3n de un canal pluvial para evitar m\u00e1s inundaciones en temporada de fuertes lluvias.<br \/>Las obras, que consistir\u00e1n en 2 mil metros cuadrados de repavimentaci\u00f3n y 300 metros de longitud a la ampliaci\u00f3n del cauce al canal de desag\u00fce, son una promesa cumplida por parte del Alcalde Francisco Trevi\u00f1o, quien inform\u00f3 que el monto de la inversi\u00f3n ser\u00e1 de 6 millones 500 mil pesos.<br \/>&#8220;Fue un compromiso que realizamos en la campa\u00f1a y hoy es una realidad. Estoy muy contento y muy complacido de que estamos ya cumpliendo con rehabilitarles el pavimento de la Avenida Las Fuentes\u2026<br \/>Y tambi\u00e9n en lo que viene a ser el pluvial, darle m\u00e1s cauce, m\u00e1s amplitud, porque en temporada de lluvia con la creciente se va inundando, se van quedando incomunicados los vecinos de algunos sectores de por aqu\u00ed, y bueno, ya con esto vamos a darle soluci\u00f3n&#8221;, expres\u00f3 el Alcalde juarense.<br \/>A\u00f1adi\u00f3 que con estas obras se beneficiar\u00e1n tambi\u00e9n los habitantes de las colonias aleda\u00f1as.<br \/>&#8220;Estamos d\u00e1ndole cumplimiento a la petici\u00f3n de todos los vecinos de Fuentes de Ju\u00e1rez, y que tambi\u00e9n viene a ayudarle aqu\u00ed a los vecinos de la Colonia Francisco Villa, Garza y Garza, as\u00ed como tambi\u00e9n a Paseo de Santa Fe&#8221;, se\u00f1al\u00f3 Paco Trevi\u00f1o.<br \/>Recalc\u00f3 que durante su Administraci\u00f3n continuar\u00e1 llevando obras a las colonias que m\u00e1s lo necesiten.<br \/>&#8220;Vamos a continuar realizando este tipo de proyectos ejecutivos para llevar m\u00e1s obras p\u00fablicas en beneficio de todos los habitantes de nuestra ciudad de Ju\u00e1rez, Nuevo Le\u00f3n&#8221;, expres\u00f3 el Alcalde.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/08\/img-20230811-wa00153101707443987460213-1024x683.jpg\" alt=\"\" class=\"wp-image-45004\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/08\/img-20230811-wa00153101707443987460213-1024x683.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/08\/img-20230811-wa00153101707443987460213-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/08\/img-20230811-wa00153101707443987460213-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/08\/img-20230811-wa00153101707443987460213.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- En beneficio de miles de habitantes de la Colonia Fuentes de Ju\u00e1rez y sectores aleda\u00f1os, el Municipio de Ju\u00e1rez inici\u00f3 obras de repavimentaci\u00f3n y ampliaci\u00f3n de un canal pluvial para evitar m\u00e1s inundaciones en temporada de fuertes lluvias.Las obras, que consistir\u00e1n en 2 mil metros cuadrados de repavimentaci\u00f3n y 300 metros de longitud [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":45003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[7016,8790,1355,1684,8791],"class_list":["post-44998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-benefician-a-familias","tag-canal-pruvial","tag-juarez","tag-paco-trevino","tag-temporada-de-lluvias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=44998"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44998\/revisions"}],"predecessor-version":[{"id":45005,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/44998\/revisions\/45005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/45003"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=44998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=44998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=44998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}