                       {"id":45447,"date":"2023-08-21T13:02:45","date_gmt":"2023-08-21T19:02:45","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=45447"},"modified":"2023-08-21T13:02:45","modified_gmt":"2023-08-21T19:02:45","slug":"condenan-a-cadena-perpetua-a-enfermera-que-mat-a-7-bebes-en-inglaterra","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/condenan-a-cadena-perpetua-a-enfermera-que-mat-a-7-bebes-en-inglaterra\/","title":{"rendered":"Condenan a cadena perpetua a enfermera que mat@ a 7 beb\u00e9s en Inglaterra"},"content":{"rendered":"<p>Inglaterra.- El juez del Tribunal de la Corona de Manchester, James Goss, conden\u00f3 a cada perpetua a una enfermera por haber matado a 7 beb\u00e9s.<\/p>\n<p>La mujer identificada como Lucy Letby, de 33 a\u00f1os, tambi\u00e9n habr\u00eda intentado matar a otros 6 peque\u00f1os m\u00e1s entre 2015 y 2016 en un centro m\u00e9dico en Chester.<\/p>\n<p>James Goss, dict\u00f3 la condena luego de dar a conocer cada uno de los cargos en contra de Lucy, de quien mencion\u00f3 &#8220;hubo premeditaci\u00f3n, c\u00e1lculo y astucia&#8221;.<\/p>\n<p>De acuerdo con las pruebas que present\u00f3 la Fiscal\u00eda en el juicio, la enfermera asesin\u00f3 a los beb\u00e9s reci\u00e9n nacidos suministr\u00e1ndoles con una jeringa intravenosa aire, en su trabajo en el hospital de la ciudad de Chester.<\/p>\n<p>Lebty no quiso ir a comparecer ante al tribunal para escuchar las historias de los pap\u00e1s de los menores, luego de que fuera declarada culpable el pasado 19 de agosto.<\/p>\n<p>FUENTE: ABC NOTICIAS<\/p>\n<p>CREDITOS FOTO : ABC NOTICIAS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inglaterra.- El juez del Tribunal de la Corona de Manchester, James Goss, conden\u00f3 a cada perpetua a una enfermera por haber matado a 7 beb\u00e9s. La mujer identificada como Lucy Letby, de 33 a\u00f1os, tambi\u00e9n habr\u00eda intentado matar a otros 6 peque\u00f1os m\u00e1s entre 2015 y 2016 en un centro m\u00e9dico en Chester. James Goss, [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":45448,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[5283,8998,4892,8999,5859],"class_list":["post-45447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-cadenaperpetua","tag-enfermeramtasietebebes","tag-inglaterra","tag-lucyletby","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/45447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=45447"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/45447\/revisions"}],"predecessor-version":[{"id":45449,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/45447\/revisions\/45449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/45448"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=45447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=45447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=45447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}