                       {"id":4618,"date":"2018-11-12T18:40:20","date_gmt":"2018-11-12T18:40:20","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=4618"},"modified":"2024-12-11T08:53:22","modified_gmt":"2024-12-11T14:53:22","slug":"surge-socavon-cierran-carretera-apodaca-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/surge-socavon-cierran-carretera-apodaca-juarez\/","title":{"rendered":"Surge socav\u00f3n; cierran carretera Apodaca-Ju\u00e1rez"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4619 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2018\/11\/7494505-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>Ju\u00e1rez, N.L.-Lo que empez\u00f3 con una grieta y un hundimiento termin\u00f3 en el desgajamiento de todo un carril de la Carretera Apodaca-Ju\u00e1rez, al fallar la reparaci\u00f3n hecha a base de puros parches de asfalto.<br \/>\nEl deslave origin\u00f3 el cierre de todo el cuerpo oriente de la carretera, a la altura del puente sobre el Arroyo La Talaverna, en Apodaca.<br \/>\nEl 16 de julio, EL NORTE public\u00f3 que la grieta de aproximadamente 15 metros de largo y el hundimiento se formaron tras las lluvias en ese punto de la carretera, con el riesgo de agravarse.<br \/>\nVecinos del Fraccionamiento Santa Anita, que se ubica a esa misma altura, se\u00f1alaron que d\u00edas despu\u00e9s la Administraci\u00f3n del ahora ex Alcalde, \u00d3scar Cant\u00fa, repar\u00f3 los da\u00f1os con rellenos de tierra y con parches de asfalto.<br \/>\n&#8220;Pero luego que se vinieron m\u00e1s lluvias se desgaj\u00f3 el carril y se cay\u00f3 al arroyo, hasta unos tubos de un drenaje pluvial se da\u00f1aron&#8221;, dijo Pedro Flores, vecino del sector.<br \/>\n&#8220;No repararon como deber\u00eda de ser, era para que hubieran reconstruido toda esa parte, no nada m\u00e1s parchado&#8221;.<br \/>\nEl desgajamiento se presenta en el carril derecho, en el sentido hacia la Colonia Pueblo Nuevo, y junto al puente sobre el Arroyo La Talaverna.<br \/>\nPor el cierre de esa secci\u00f3n, el cuerpo contrario fue habilitado a contraflujo a lo largo de cientos de metros.<br \/>\nJunto al desgajamiento todav\u00eda se aprecian parte de los parches con los que se taparon la grieta y el hundimiento.<br \/>\nAdem\u00e1s del deslave, el revestimiento de concreto en un talud del arroyo tambi\u00e9n presenta fuertes da\u00f1os.<br \/>\nLos vecinos se\u00f1alaron que las lluvias durante septiembre y octubre agravaron las afectaciones.<\/p>\n<p style=\"text-align: justify;\">FUENTE: EL NORTE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.-Lo que empez\u00f3 con una grieta y un hundimiento termin\u00f3 en el desgajamiento de todo un carril de la Carretera Apodaca-Ju\u00e1rez, al fallar la reparaci\u00f3n hecha a base de puros parches de asfalto. El deslave origin\u00f3 el cierre de todo el cuerpo oriente de la carretera, a la altura del puente sobre el Arroyo [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4619,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[476,2155],"class_list":["post-4618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-carrtera-apodaca-juarez","tag-socavon"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=4618"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4618\/revisions"}],"predecessor-version":[{"id":65502,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4618\/revisions\/65502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=4618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=4618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=4618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}