                       {"id":46206,"date":"2023-09-06T11:46:30","date_gmt":"2023-09-06T17:46:30","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=46206"},"modified":"2023-09-06T11:46:30","modified_gmt":"2023-09-06T17:46:30","slug":"la-india-cambia-de-nombre-gobierno-comienza-a-usar-bharat-en-documentos-oficiales","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/la-india-cambia-de-nombre-gobierno-comienza-a-usar-bharat-en-documentos-oficiales\/","title":{"rendered":"\u00bfLa India cambia de nombre? Gobierno comienza a usar \u2018Bharat\u2019 en documentos oficiales\u00a0"},"content":{"rendered":"<p>El gobierno del primer ministro Narendra Modi reemplaz\u00f3 el nombre India por una palabra s\u00e1nscrita en las invitaciones a cenar enviadas a los invitados a la cumbre del Grupo de los 20 de esta semana, en una medida que refleja los esfuerzos de su partido nacionalista hind\u00fa para eliminar lo que considera nombres de la era colonial.<\/p>\n<p>El presidente indio Droupadi Murmu es referido como \u201cPresidente de Bharat\u201d en lugar de \u201cPresidente de la India\u201d en la invitaci\u00f3n enviada a los asistentes del G20. La naci\u00f3n de m\u00e1s de 1.4 millones de personas es conocida oficialmente por dos nombres, India y Bharat, pero el primero es el m\u00e1s utilizado, tanto a nivel nacional como internacional.<\/p>\n<p>Bharat es una antigua palabra s\u00e1nscrita que muchos historiadores creen que se remonta a los primeros textos hind\u00faes. La palabra tambi\u00e9n significa India en hindi.<\/p>\n<p>El cambio en la nomenclatura est\u00e1 respaldado por funcionarios del Partido Bharatiya Janata de Modi. Argumentan que el nombre India fue introducido por los coloniales brit\u00e1nicos y es un \u201cs\u00edmbolo de esclavitud\u201d.<\/p>\n<p>\u201cOtro golpe a la mentalidad de esclavitud\u201d, dijo el principal funcionario electo del estado de Uttarakhand, Pushkar Singh Dhami, en Twitter. Dhami, quien es l\u00edder del partido gobernante de Modi, comparti\u00f3 la invitaci\u00f3n a cenar enviada a los invitados del G20 en su publicaci\u00f3n.<\/p>\n<p>El partido de Modi ha intentado durante mucho tiempo borrar nombres relacionados con el pasado mogol y colonial de la India.<\/p>\n<p>Las disputas sobre \u201cIndia\u201d versus \u201cBharat\u201d han ganado terreno desde que los partidos de oposici\u00f3n anunciaron en julio una nueva alianza, llamada INDIA, para derrocar a Modi y derrotar a su partido antes de las elecciones nacionales de 2024. El acr\u00f3nimo significa Alianza Nacional India para el Desarrollo Inclusivo.<\/p>\n<p>Desde entonces, algunos funcionarios del partido de Modi han exigido que el pa\u00eds se llame Bharat en lugar de India.<\/p>\n<p>FUENTE: EL FINANCIERO<\/p>\n<p>CR\u00c9DITOS FOTO: TWITTER @PUSHKARDHAMI\/ EL FINANCIERO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno del primer ministro Narendra Modi reemplaz\u00f3 el nombre India por una palabra s\u00e1nscrita en las invitaciones a cenar enviadas a los invitados a la cumbre del Grupo de los 20 de esta semana, en una medida que refleja los esfuerzos de su partido nacionalista hind\u00fa para eliminar lo que considera nombres de la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":46207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[9269,7642,9270,5859],"class_list":["post-46206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-bharat","tag-india","tag-simbolo-de-esclavitud","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=46206"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46206\/revisions"}],"predecessor-version":[{"id":46208,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46206\/revisions\/46208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/46207"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=46206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=46206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=46206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}