                       {"id":46269,"date":"2023-09-07T07:01:38","date_gmt":"2023-09-07T13:01:38","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=46269"},"modified":"2023-09-07T07:04:01","modified_gmt":"2023-09-07T13:04:01","slug":"muere-despachadora-en-explosion-de-gasera","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/muere-despachadora-en-explosion-de-gasera\/","title":{"rendered":"Muere despachadora en explosi\u00f3n de gasera"},"content":{"rendered":"\n<p><br>Ju\u00e1rez, N.L.-Una mujer sin vida y una persona lesionada, fue el saldo fatal de la explosi\u00f3n en una estaci\u00f3n de gas L.P. la tarde de ayer en la avenida Te\u00f3filo Salinas en la colonia Villas de San Jos\u00e9.<br>Los acontecimientos se suscitaron cuando Mar\u00eda Isabela Hern\u00e1ndez Marcelino en 30 a 35 a\u00f1os, despachadora del negocio denominado &#8220;Saga&#8221;, recargana el combustible en una camioneta Ford, cuando sobrevino la explosi\u00f3n.<\/p>\n\n\n\n<p>En el accidente tambi\u00e9n result\u00f3 con quemaduras de primero y segundo grado Alfredo Chavarr\u00eda Aguilar de 68 a\u00f1os, propietario del veh\u00edculo y con donicilio en la colonia Praderas de San Juan.<br \/>Al lugar arribaron elementos de Protecci\u00f3n Civil de Ju\u00e1rez, al mando de Francisco Moyar y Erick Cavazos Cavazos, titular estatal de la misma dependencia, quienes en entrevista con La \u00daltima Palabra dieron los pormenores de los hechos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.-Una mujer sin vida y una persona lesionada, fue el saldo fatal de la explosi\u00f3n en una estaci\u00f3n de gas L.P. la tarde de ayer en la avenida Te\u00f3filo Salinas en la colonia Villas de San Jos\u00e9.Los acontecimientos se suscitaron cuando Mar\u00eda Isabela Hern\u00e1ndez Marcelino en 30 a 35 a\u00f1os, despachadora del negocio denominado [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":46268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[9290,9291,9292],"class_list":["post-46269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-explosion-gasera","tag-muere-despachadora","tag-una-mujer-sin-vida"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=46269"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46269\/revisions"}],"predecessor-version":[{"id":46270,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46269\/revisions\/46270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/46268"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=46269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=46269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=46269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}