                       {"id":46377,"date":"2023-09-08T11:39:11","date_gmt":"2023-09-08T17:39:11","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=46377"},"modified":"2023-09-08T11:39:11","modified_gmt":"2023-09-08T17:39:11","slug":"captan-a-perrita-malabarista-trabajando-con-su-dueno-en-calles-de-monterrey","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/captan-a-perrita-malabarista-trabajando-con-su-dueno-en-calles-de-monterrey\/","title":{"rendered":"Captan a perrita malabarista trabajando con su due\u00f1o en calles de Monterrey"},"content":{"rendered":"<p>Monterrey. &#8211; Una perrita regiomontana se ha hecho viral en redes sociales, tras ser captada trabajando con su due\u00f1o, haciendo malabares y trucos en un cruce peatonal de la avenida Paseo de los Leones en Monterrey, Nuevo Le\u00f3n.<\/p>\n<p>El video fue subido a la plataforma de TikTok, por una usuaria identificada como Esperanza Carrillo, quien fue la persona que grab\u00f3 a la canina atrapando una pelota y rodando en el suelo, enamorando y enterneciendo as\u00ed a cientos de internautas.<\/p>\n<p>La grabaci\u00f3n fue tomada desde el interior del veh\u00edculo de Esperanza, en ella se observa al animalito haciendo algunos trucos con su pelota, se da vueltas en el suelo, salta y se sienta en un banco, como parte del trabajo que hace junto a su due\u00f1o, quien sale a las calles de Monterrey para ganar dinero.<\/p>\n<p>Algunas personas quienes ya la hab\u00edan visto y conocido, destacaron su inteligencia, ternura y obediencia, ya que la perrita hace todo lo que el hombre le pida.<\/p>\n<p>En el tiktok se observa que el sujeto le ordena sentarse en un banco blanco y a esperarlo sin moverse, el lomito se queda quieto, mientras que su due\u00f1o pasa por los carros para recolectar dinero.<\/p>\n<p>Son dos perritas las que acompa\u00f1an al hombre y de acuerdo con usuarios de redes se llaman Miel y Lili, sin embargo, hasta el momento no se han confirmado las identidades de las caninas.<\/p>\n<p>Adem\u00e1s, mencionaron que el amo de las perritas, a quien lo se\u00f1alaron de ser muy buena persona, tratarlas muy bien y con mucho cari\u00f1o a sus mascotitas.<\/p>\n<p>Destacaron que \u00e9l solo trabaja con ellas en ratos cuando no hay sol, para no exponerlas a altas temperaturas, y si les tiene su alimento y agua.<\/p>\n<p>&#8220;Se llaman Lili y Miel, y el se\u00f1or las trata super bien, son un amor de persona&#8221;, &#8220;solo trabaja en ratios cuando ya no hay sol y est\u00e1n bien gorditas&#8221;, tambi\u00e9n se pone en Madero y Venustiano, los tiene bien cuidados, comidos y todo&#8221;, &#8220;tuve la fortuna de conocer al se\u00f1or y lleg\u00f3 con una de las perritas en su moto las trata con tanto cari\u00f1o&#8221;, fueron algunos de los comentarios.<\/p>\n<p>FUENTE: ABC NOTICIAS<\/p>\n<p>Cr\u00e9ditos: milenio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey. &#8211; Una perrita regiomontana se ha hecho viral en redes sociales, tras ser captada trabajando con su due\u00f1o, haciendo malabares y trucos en un cruce peatonal de la avenida Paseo de los Leones en Monterrey, Nuevo Le\u00f3n. El video fue subido a la plataforma de TikTok, por una usuaria identificada como Esperanza Carrillo, quien [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":46378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[9326,5895,9327,5859],"class_list":["post-46377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-malabarista","tag-monterrey","tag-perrita","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=46377"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46377\/revisions"}],"predecessor-version":[{"id":46379,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46377\/revisions\/46379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/46378"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=46377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=46377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=46377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}