                       {"id":46750,"date":"2023-09-17T17:40:35","date_gmt":"2023-09-17T23:40:35","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=46750"},"modified":"2023-09-17T17:42:48","modified_gmt":"2023-09-17T23:42:48","slug":"resulta-motociclista-lesionado-en-choque-5","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/resulta-motociclista-lesionado-en-choque-5\/","title":{"rendered":"Resulta motociclista lesionado en choque"},"content":{"rendered":"\n<p>Ju\u00e1rez, N.L.-Un joven con graves heridas, fue el saldo de un choque entre un auto y una motocicleta esta tarde en la carretera a Reynosa, frente a la colonia Villas de Oriente.<br>Los hechos ocurrieron cuando Christan Jon\u00e1s G. de 20 a\u00f1os de edad, conduc\u00eda su motocicleta 250 por la carretera a Reynosa y se le atraves\u00f3 al paso el auto Aveo, modelo 2021, placas 59-KVU del estado de Nuevo Le\u00f3n, conducido por Jos\u00e9 Sergio N. De 60 a\u00f1os con domicilio en la colonia Zaragoza, de Guadalupe, Nuevo Le\u00f3n.<br>El conductor de la motocicleta, quien es vecino de la colonia Praderas de San Juan, sufri\u00f3 una herida de 10 cent\u00edmetros en forma circular en la extremidad superior derecha a la altura de la mu\u00f1eca, asi mismo contusi\u00f3n con hematomas en \u00e1rea de t\u00f3rax y abdomen, laceraciones en \u00e1rea de mand\u00edbula superior e inferior y p\u00f3mulo izquierdo, aparte de encontrarse desorientado.<br>El herido fue trasladado a la Cl\u00ednica 20 por param\u00e9dicos de Protecci\u00f3n Civil de Ju\u00e1rez, mientras elementos de Tr\u00e1nsito municipal realizaban las debidas investigaciones para consignar el accidente al Ministerio P\u00fablico Especializado en Asuntos Viales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.-Un joven con graves heridas, fue el saldo de un choque entre un auto y una motocicleta esta tarde en la carretera a Reynosa, frente a la colonia Villas de Oriente.Los hechos ocurrieron cuando Christan Jon\u00e1s G. de 20 a\u00f1os de edad, conduc\u00eda su motocicleta 250 por la carretera a Reynosa y se le [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":46749,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[9461,8609,5128],"class_list":["post-46750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-choca-contra-carro","tag-choca-motociclista","tag-lesionado"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=46750"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46750\/revisions"}],"predecessor-version":[{"id":46751,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/46750\/revisions\/46751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/46749"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=46750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=46750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=46750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}