                       {"id":47061,"date":"2023-09-22T11:44:05","date_gmt":"2023-09-22T17:44:05","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=47061"},"modified":"2023-09-22T11:44:05","modified_gmt":"2023-09-22T17:44:05","slug":"entregan-dos-patrullas-para-combatir-la-violencia-contra-la-mujer","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/entregan-dos-patrullas-para-combatir-la-violencia-contra-la-mujer\/","title":{"rendered":"Entregan dos patrullas para combatir la violencia contra la mujer\u00a0"},"content":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.-Este viernes el Gobierno de Cadereyta entreg\u00f3 dos patrullas de Polic\u00eda para la atenci\u00f3n pronta de casos de violencia de g\u00e9nero que se presenten en el municipio y trabajar\u00e1n de la mano con el Instituto de la Mujer.<\/p>\n<p>El evento se realiz\u00f3 en la explanada de la Plaza Principal Miguel Hidalgo, encabezado por el alcalde Cosme Juli\u00e1n Leal, regidoras del Ayuntamiento, funcionarias municipales y el Secretario de Seguridad P\u00fablica, \u00c1ngel Mario Rodr\u00edguez.<\/p>\n<p>\u201cEstas son unidades para reforzar la una atenci\u00f3n pronta en casos de violencia de g\u00e9nero, violencia familiar y vamos a seguir trabajando en estrategias eficaces para erradicar al m\u00e1ximo los casos en los que las mujeres son violentadas, estar\u00e1n enfocadas en eso estas patrullas\u201d, dijo el presidente municipal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.-Este viernes el Gobierno de Cadereyta entreg\u00f3 dos patrullas de Polic\u00eda para la atenci\u00f3n pronta de casos de violencia de g\u00e9nero que se presenten en el municipio y trabajar\u00e1n de la mano con el Instituto de la Mujer. El evento se realiz\u00f3 en la explanada de la Plaza Principal Miguel Hidalgo, encabezado por [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":47062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[3840,9563,5859,2313],"class_list":["post-47061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-cadereyta-jimenez-nl","tag-entregan-patrullas","tag-ultimas-noticias","tag-violencia-contra-la-mujer"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/47061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=47061"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/47061\/revisions"}],"predecessor-version":[{"id":47063,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/47061\/revisions\/47063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/47062"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=47061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=47061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=47061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}