                       {"id":47431,"date":"2023-09-28T09:23:51","date_gmt":"2023-09-28T15:23:51","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=47431"},"modified":"2023-09-28T09:23:51","modified_gmt":"2023-09-28T15:23:51","slug":"reconoce-hgz-no-33-del-imss-nuevo-leon-a-30-familias-de-heroes-y-heroinas-que-donaron-organos","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/reconoce-hgz-no-33-del-imss-nuevo-leon-a-30-familias-de-heroes-y-heroinas-que-donaron-organos\/","title":{"rendered":"Reconoce HGZ No. 33 del IMSS Nuevo Le\u00f3n a 30 familias de h\u00e9roes y hero\u00ednas que donaron \u00f3rganos"},"content":{"rendered":"<p>Entregan reconocimientos y guardan un minuto de silencio y aplausos para honrar la memoria de los donantes fallecidos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-47433\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0069-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0069-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0069-1024x682.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0069-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0069.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Conmemora esta unidad la Semana Nacional de la Donaci\u00f3n y Trasplante de \u00d3rganos y Tejidos, del 25 al 29 de septiembre.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-47434\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0067-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0067-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0067-1024x682.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0067-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0067.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Como agradecimiento al altruismo y solidaridad en momentos de duelo, el Hospital General de Zona (HGZ) No. 33 del Instituto Mexicano del Seguro Social (IMSS) en Nuevo Le\u00f3n realiz\u00f3 una emotiva ceremonia para 30 familias de pacientes que, al fallecer, donaron sus \u00f3rganos a personas que necesitaban un trasplante para seguir viviendo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-47435\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0066-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0066-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0066-1024x682.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0066-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/09\/IMG-20230927-WA0066.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Las familias de pacientes donadores se reunieron en el auditorio del HGZ No. 33, en Monterrey, donde se les reconoci\u00f3 como h\u00e9roes y hero\u00ednas.<\/p>\n<p>La directora del hospital, doctora Mar\u00eda de Jes\u00fas Castillo Mart\u00ednez, encabez\u00f3 la ceremonia en la que se entreg\u00f3 un reconocimiento a nombre de cada uno de los donadores, se honraron sus memorias con un minuto de silencio y aplausos al escuchar cada uno de sus nombres.<\/p>\n<p>Castillo Mart\u00ednez agradeci\u00f3 al Comit\u00e9 de Procuraci\u00f3n de \u00d3rganos, encabezado por la doctora Margarita Marina Arias Pecina, y a los integrantes del grupo de trasplantes por el esfuerzo permanente en la dif\u00edcil tarea de conseguir \u00f3rganos en donaci\u00f3n para poder realizar exitosos trasplantes.<\/p>\n<p>Se dirigi\u00f3 a los familiares para reconocer el valor de donar en momentos de dolor ante la p\u00e9rdida de sus seres queridos. \u201cAqu\u00ed hay un equipo comprometido para realizar esta tarea nada f\u00e1cil, pero gracias a ustedes, fue posible realizar un trasplante para que otras personas prolongar\u00e1n su vida\u201d.<\/p>\n<p>El grupo se dirigi\u00f3 al lobby del hospital para colocar el nombre de su ser querido en una hoja que forma parte del \u201c\u00c1rbol de la Vida\u201d, mismo que simboliza la conexi\u00f3n con la familia y con la tierra.<\/p>\n<p>De esta manera, como cada a\u00f1o, el Comit\u00e9 de Donaci\u00f3n del HGZ No. 33 del IMSS en Nuevo Le\u00f3n conmemora la Semana Nacional de Donaci\u00f3n y Trasplante de \u00d3rganos y Tejidos, del 25 al 29 de septiembre.<\/p>\n<p>Desde el 2009. el hospital inici\u00f3 su actividad de trasplantes de ri\u00f1\u00f3n y c\u00f3rneas y, por lo tanto, una din\u00e1mica actividad para fortalecer la cultura de la donaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entregan reconocimientos y guardan un minuto de silencio y aplausos para honrar la memoria de los donantes fallecidos. &nbsp; &nbsp; &nbsp; Conmemora esta unidad la Semana Nacional de la Donaci\u00f3n y Trasplante de \u00d3rganos y Tejidos, del 25 al 29 de septiembre. &nbsp; &nbsp; &nbsp; &nbsp; Como agradecimiento al altruismo y solidaridad en momentos de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":47432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[870,9658,1249,5859],"class_list":["post-47431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-donacion-de-organos","tag-familias-de-heroes","tag-imss","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/47431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=47431"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/47431\/revisions"}],"predecessor-version":[{"id":47436,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/47431\/revisions\/47436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/47432"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=47431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=47431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=47431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}