                       {"id":47759,"date":"2023-10-03T12:41:39","date_gmt":"2023-10-03T18:41:39","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=47759"},"modified":"2023-10-03T12:41:39","modified_gmt":"2023-10-03T18:41:39","slug":"atacan-a-balzos-a-hombres-afuera-de-farmacias-en-monterrey-y-guadalupe-hay-4-heridos","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/atacan-a-balzos-a-hombres-afuera-de-farmacias-en-monterrey-y-guadalupe-hay-4-heridos\/","title":{"rendered":"Atacan a bal@zos a hombres afuera de farmacias en Monterrey y Guadalupe; hay 4 heridos"},"content":{"rendered":"<p>Al exterior de una farmacia, dos hombres fueron atacados a balazos y resultaron gravemente heridos ayer en Monterrey.<\/p>\n<p>La agresi\u00f3n se registr\u00f3 minutos antes de las 21:00 horas en el cruce de Cipr\u00e9s y F\u00e9lix U. G\u00f3mez, en la colonia Moderna.<\/p>\n<p>Presuntamente las v\u00edctimas caminaban por la zona cuando recibieron m\u00faltiples disparos por arma de fuego, que accionaron los tripulantes de una motocicleta.<\/p>\n<p>Una fuente inform\u00f3 que uno de los lesionados presentaba dos balazos en la cabeza y dos m\u00e1s en el abdomen, por lo que fue trasladado por param\u00e9dicos de Cruz Roja a un hospital.<\/p>\n<p>Mientras que la segunda v\u00edctima fue trasladada por sus familiares en un veh\u00edculo particular. En el lugar localizaron varios casquillos de armas cortas.<\/p>\n<p>Asimismo, en la colonia Am\u00e9rica Obrera en el municipio de Guadalupe se registr\u00f3 un hecho similar donde otros dos hombres resultaron lesionados luego de ser atacados a balazos afuera de una farmacia ubicada en las calles de Francisco Sarabia y Las Am\u00e9ricas.<\/p>\n<p>De acuerdo a una fuente las v\u00edctimas identificadas como Javier Molina Casta\u00f1eda de 27 a\u00f1os y Julio C\u00e9sar Aguirre de 34 reci\u00e9n hab\u00edan salido de la farmacia y subieron a bordo de su camioneta, cuando dos hombres a bordo de una motocicleta dispararon en su contra.<\/p>\n<p>Sin embargo, al intentar huir chocaron su camioneta contra un veh\u00edculo estacionado.<\/p>\n<p>Javier result\u00f3 con heridas en el cr\u00e1neo mientras que Julio qui\u00e9n tiene antecedentes penales por Robo, sufri\u00f3 heridas por esquirlas en el brazo.<\/p>\n<p>Al lugar arribaron elementos de la polic\u00eda municipal, Fuerza Civil y de la Agencia Estatal de Investigaciones, quienes ya indagan el caso.<\/p>\n<p>FUENTE: MILENIO<\/p>\n<p>Cr\u00e9ditos foto: milenio<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al exterior de una farmacia, dos hombres fueron atacados a balazos y resultaron gravemente heridos ayer en Monterrey. La agresi\u00f3n se registr\u00f3 minutos antes de las 21:00 horas en el cruce de Cipr\u00e9s y F\u00e9lix U. G\u00f3mez, en la colonia Moderna. Presuntamente las v\u00edctimas caminaban por la zona cuando recibieron m\u00faltiples disparos por arma de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":47760,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[9762,9763,6576,4359,5895,5859],"class_list":["post-47759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-ataqueablazos","tag-farmacia","tag-guadalupe","tag-heridos","tag-monterrey","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/47759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=47759"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/47759\/revisions"}],"predecessor-version":[{"id":47761,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/47759\/revisions\/47761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/47760"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=47759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=47759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=47759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}