                       {"id":4820,"date":"2018-11-23T00:30:57","date_gmt":"2018-11-23T00:30:57","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=4820"},"modified":"2024-12-11T08:53:24","modified_gmt":"2024-12-11T14:53:24","slug":"mata-a-su-cunada-y-la-tira-en-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/mata-a-su-cunada-y-la-tira-en-juarez\/","title":{"rendered":"Mata a su cu\u00f1ada y la tira en Ju\u00e1rez"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4821 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2018\/11\/1-22.jpg\" alt=\"\" width=\"254\" height=\"196\" \/>CD. BENITO JU\u00c1REZ, N.L.-<br \/>\nUn hombre asesin\u00f3 a su cu\u00f1ada de 40 cuchilladas al tener un pleito por una propiedad, cuando la llev\u00f3 a fuerzas a despoblado y la atac\u00f3 violentamente.<br \/>\nLa mujer se hab\u00eda citado con una hermana de su pareja para hablar sobre el inmueble que ambos habitaron hasta hace unos meses, pero el agresor la subi\u00f3 a la fuerza a una camioneta para traerla a la colonia Anzures de este municipio.<br \/>\nMar\u00eda Aurora Hern\u00e1ndez, de 48 a\u00f1os de edad, es la v\u00edctima mortal quien habitaba en la colonia Valle de Huinal\u00e1, en Apodaca.<br \/>\nEl hallazgo de su cuerpo fue encontrado la noche lunes en la orilla de la carretera Apodaca-Ju\u00e1rez a la altura de la calle Camino a San Roque, frente a la colonia Anzures.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CD. BENITO JU\u00c1REZ, N.L.- Un hombre asesin\u00f3 a su cu\u00f1ada de 40 cuchilladas al tener un pleito por una propiedad, cuando la llev\u00f3 a fuerzas a despoblado y la atac\u00f3 violentamente. La mujer se hab\u00eda citado con una hermana de su pareja para hablar sobre el inmueble que ambos habitaron hasta hace unos meses, pero [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4821,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,8,10],"tags":[197],"class_list":["post-4820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad","category-seguridad-juarez","tag-asesino-cunada"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=4820"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4820\/revisions"}],"predecessor-version":[{"id":65620,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4820\/revisions\/65620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=4820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=4820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=4820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}