                       {"id":49980,"date":"2023-11-13T13:11:47","date_gmt":"2023-11-13T19:11:47","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=49980"},"modified":"2023-11-13T13:11:47","modified_gmt":"2023-11-13T19:11:47","slug":"quedan-40-obreros-atrapados-en-la-india-tras-derrumbarse-tunel","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/quedan-40-obreros-atrapados-en-la-india-tras-derrumbarse-tunel\/","title":{"rendered":"Quedan 40 obreros atrapados en la India tras derrumbarse t\u00fanel"},"content":{"rendered":"<p>Al menos 40 obreros quedaron atrapados el domingo tras derrumbarse el t\u00fanel de carretera que estaban construyendo en el estado de Uttarakhand, en el norte de India, indic\u00f3 un responsable de los servicios de rescate.<\/p>\n<p>&#8220;Alrededor de 200 metros del t\u00fanel se vinieron abajo&#8221;, declar\u00f3 a la AFP Durgesh Rathodi desde el lugar.<\/p>\n<p>&#8220;Unos 40 o 41 trabajadores est\u00e1n atrapados dentro. Se est\u00e1 suministrando ox\u00edgeno a trav\u00e9s de los escombros, pero est\u00e1n cayendo m\u00e1s cascotes a medida que los rescatistas intentan retirar la obstrucci\u00f3n&#8221;, a\u00f1adi\u00f3.<\/p>\n<p>El derrumbe se produjo temprano el domingo en la regi\u00f3n del Himalaya, cuando un grupo de trabajadores estaba saliendo del t\u00fanel y llegaba un equipo de reemplazo.<\/p>\n<p>El t\u00fanel de 4,5 kil\u00f3metros de largo se est\u00e1 construyendo entre Silkyara y Dandalgaon para conectar los dos importantes santuarios hind\u00faes de Uttarkashi y Yamnotri.<\/p>\n<p>Las im\u00e1genes publicadas por los equipos de rescate muestran enormes bloques de hormig\u00f3n bloqueando el t\u00fanel, con barras de metal retorcidas en el techo que sobresalen de los escombros.<\/p>\n<p>&#8220;Recemos para que los trabajadores atrapados dentro del t\u00fanel salgan sanos y salvos&#8221;, escribi\u00f3 el ministro principal de Uttarakhand, Pushkar Singh Dhami, en X (antes Twitter).<\/p>\n<p>Un agente de la polic\u00eda dijo a la agencia Press Trust of India que los rescatistas se mostraban &#8220;muy optimistas&#8221; sobre el desenlace.<\/p>\n<p>Este t\u00fanel forma parte del proyecto Char Dam Road, dise\u00f1ado para mejorar las conexiones con algunos de los santuarios hind\u00faes m\u00e1s populares del pa\u00eds, as\u00ed como con las regiones cercanas a la frontera con China.<\/p>\n<p>Los accidentes en grandes obras de construcci\u00f3n de infraestructuras son recurrentes en India.<\/p>\n<p>FUENTE:LA JORNADA<\/p>\n<p>Cr\u00e9ditos foto: TELEDIARIO<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos 40 obreros quedaron atrapados el domingo tras derrumbarse el t\u00fanel de carretera que estaban construyendo en el estado de Uttarakhand, en el norte de India, indic\u00f3 un responsable de los servicios de rescate. &#8220;Alrededor de 200 metros del t\u00fanel se vinieron abajo&#8221;, declar\u00f3 a la AFP Durgesh Rathodi desde el lugar. &#8220;Unos 40 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":49981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[7791,7642,10527,10528,10526,5859],"class_list":["post-49980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-derrumbe","tag-india","tag-obreros","tag-quedanatrapados","tag-tunel","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/49980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=49980"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/49980\/revisions"}],"predecessor-version":[{"id":49982,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/49980\/revisions\/49982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/49981"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=49980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=49980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=49980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}