                       {"id":50284,"date":"2023-11-17T18:01:49","date_gmt":"2023-11-18T00:01:49","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=50284"},"modified":"2023-11-17T18:01:49","modified_gmt":"2023-11-18T00:01:49","slug":"dos-lesionados-tras-cerrarles-paso-trailer","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/dos-lesionados-tras-cerrarles-paso-trailer\/","title":{"rendered":"Dos lesionados tras cerrarles paso tr\u00e1iler"},"content":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- La tarde de este viernes el conductor de una motocicleta y su acompa\u00f1ante resultaron lesionados, esto despu\u00e9s de que un tr\u00e1iler les cerrara el paso al tratar de dar vuelta en &#8220;u&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50286\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-34-427-300x135.jpg\" alt=\"\" width=\"300\" height=\"135\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-34-427-300x135.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-34-427-1024x461.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-34-427-768x346.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-34-427-1536x691.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-34-427.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>El percance se registr\u00f3 en el boulevard Independencia frente a los campos de la Uni\u00f3n Ganadera, en el municipio de Cadereyta.<\/p>\n<p>Presuntamente el ch\u00f3fer del tr\u00e1iler &#8220;espeje\u00f3&#8221; pero no vi\u00f3 la motocicleta por lo que trat\u00f3 de dar vuelta en &#8220;u&#8221; por lo que el motociclista junto con su compa\u00f1ero, trataron de evitar el golpe pero derraparon y cayeron al suelo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50287\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-57-216-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-57-216-300x225.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-57-216-1024x768.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-57-216-768x576.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/Picsart_23-11-17_17-28-57-216.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Los dos hombres de alrededor de 30 a\u00f1os de edad, quienes viajaban en una motocicleta Dinamo de color gris con negro, hasta el momento no han sido identificados, sin embargo, fueron trasladados por param\u00e9dicos de Servicios de Emergencia Cadereyta a la cl\u00ednica Valle para su atenci\u00f3n m\u00e9dica.<\/p>\n<p>Agentes de Vialidad y Tr\u00e1nsito abanderaron el sitio para evitar otro percance e iniciar las pesquisas correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- La tarde de este viernes el conductor de una motocicleta y su acompa\u00f1ante resultaron lesionados, esto despu\u00e9s de que un tr\u00e1iler les cerrara el paso al tratar de dar vuelta en &#8220;u&#8221;. &nbsp; &nbsp; &nbsp; El percance se registr\u00f3 en el boulevard Independencia frente a los campos de la Uni\u00f3n Ganadera, en [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":50285,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[4196,3840,5859],"class_list":["post-50284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-accidente","tag-cadereyta-jimenez-nl","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=50284"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50284\/revisions"}],"predecessor-version":[{"id":50288,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50284\/revisions\/50288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/50285"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=50284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=50284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=50284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}