                       {"id":50344,"date":"2023-11-21T11:57:00","date_gmt":"2023-11-21T17:57:00","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=50344"},"modified":"2023-11-21T11:57:00","modified_gmt":"2023-11-21T17:57:00","slug":"ataque-a-balazos-deja-a-un-joven-sin-vida-en-guadalupe","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/ataque-a-balazos-deja-a-un-joven-sin-vida-en-guadalupe\/","title":{"rendered":"Ataque a balazos deja a un joven sin vida en Guadalupe"},"content":{"rendered":"<p>Monterrey. &#8211; Un hombre fue asesinado a balazos en su domicilio ubicado en la calle Del Veranio, entre Del Astro y Del Jard\u00edn, en la colonia Valles del Sol, en el municipio de Guadalupe.<\/p>\n<p>Tras el reporte de las detonaciones por arma de fuego, alrededor de las 18:35 horas hasta el lugar acudieron elementos de la polic\u00eda municipal de Ju\u00e1rez, quienes confirmaron el hallazgo de la persona sin signos vitales.<\/p>\n<p>Seg\u00fan fuentes, el joven recibi\u00f3 al menos tres impactos de bala a corta distancia por presuntos civiles armados, quienes presumiblemente dispararon desde una camioneta SUV de color blanco.<\/p>\n<p>De acuerdo con la informaci\u00f3n brindada por parte de las autoridades, el ahora occiso fue identificado como Aldair Uriel Luna, de tan solo 18 a\u00f1os de edad.<\/p>\n<p>Asimismo, fue se\u00f1alado por las autoridades como presunto vendedor de sustancias ilegales; seg\u00fan refieren, contaba con antecedentes penales por delitos contra la salud y robo con violencia.<\/p>\n<p>Autoridades de la Agencia Estatal de Investigaciones (AEI) se encuentran en la escena para investigar este nuevo episodio de violencia en la entidad de Nuevo Le\u00f3n, el cual es resguardado por autoridades municipales del Municipio de Ju\u00e1rez.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey. &#8211; Un hombre fue asesinado a balazos en su domicilio ubicado en la calle Del Veranio, entre Del Astro y Del Jard\u00edn, en la colonia Valles del Sol, en el municipio de Guadalupe. Tras el reporte de las detonaciones por arma de fuego, alrededor de las 18:35 horas hasta el lugar acudieron elementos de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":50346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[5482,6576,10629,5859],"class_list":["post-50344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-ataqueabalazos","tag-guadalupe","tag-jovenasesinado","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=50344"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50344\/revisions"}],"predecessor-version":[{"id":50347,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50344\/revisions\/50347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/50346"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=50344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=50344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=50344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}