                       {"id":50640,"date":"2023-11-27T12:17:16","date_gmt":"2023-11-27T18:17:16","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=50640"},"modified":"2023-11-27T12:17:16","modified_gmt":"2023-11-27T18:17:16","slug":"se-registra-el-primer-caso-de-gripe-porcina-en-un-ser-humano-en-reino-unido","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/se-registra-el-primer-caso-de-gripe-porcina-en-un-ser-humano-en-reino-unido\/","title":{"rendered":"Se registra el primer caso de gripe porcina en un ser humano en Reino Unido"},"content":{"rendered":"<p>La Agencia de Seguridad Sanitaria del Reino Unido (UKHSA, por sus siglas en ingl\u00e9s) inform\u00f3 que se detect\u00f3 el primer caso de gripe porcina en un ser humano en el pa\u00eds, por lo que llam\u00f3 a los habitantes a tomar precauciones, sobre todo las que tienen afecciones m\u00e9dicas existentes.<\/p>\n<p>Destac\u00f3 que el \u00fanico caso humano confirmado de gripe A (H1N2) v fue detectado tras la vigilancia nacional de rutina de la gripe. El m\u00e9dico de cabecera hizo pruebas a una persona despu\u00e9s de experimentar s\u00edntomas respiratorios .<\/p>\n<p>Mencion\u00f3 que la persona en qui\u00e9n se detect\u00f3 sufri\u00f3 una enfermedad leve y se ha recuperado por completo, pero hasta el momento la fuente de infecci\u00f3n no se ha determinado y sigue bajo investigaci\u00f3n.<\/p>\n<p>Asimismo, dijo que se est\u00e1n realizando las investigaciones para conocer c\u00f3mo el individuo adquiri\u00f3 la infecci\u00f3n y evaluar si existen m\u00e1s casos asociados, con el objetivo de detener una propagaci\u00f3n de la enfermedad.<\/p>\n<p>Por otra parte, la directora veterinaria Christine Middlemiss, dijo que los criadores de cerdos tambi\u00e9n deben informar inmediatamente a su veterinario local de cualquier sospecha de gripe porcina en sus piaras.<\/p>\n<p>FUENTE: ADN40<\/p>\n<p>Cr\u00e9ditos foto: PeriodicoMOTIVAR<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Agencia de Seguridad Sanitaria del Reino Unido (UKHSA, por sus siglas en ingl\u00e9s) inform\u00f3 que se detect\u00f3 el primer caso de gripe porcina en un ser humano en el pa\u00eds, por lo que llam\u00f3 a los habitantes a tomar precauciones, sobre todo las que tienen afecciones m\u00e9dicas existentes. Destac\u00f3 que el \u00fanico caso humano [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":50641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[10714,10716,8365,10715,5859],"class_list":["post-50640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-gripeporcina","tag-primercaso","tag-reinounido","tag-sintomasrespiratorios","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=50640"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50640\/revisions"}],"predecessor-version":[{"id":50642,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50640\/revisions\/50642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/50641"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=50640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=50640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=50640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}