                       {"id":50766,"date":"2023-11-29T14:55:45","date_gmt":"2023-11-29T20:55:45","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=50766"},"modified":"2023-11-29T14:55:45","modified_gmt":"2023-11-29T20:55:45","slug":"entrega-paco-trevino-apoyo-a-primaria-para-aula-inteligente","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/entrega-paco-trevino-apoyo-a-primaria-para-aula-inteligente\/","title":{"rendered":"Entrega Paco Trevi\u00f1o apoyo a primaria para aula inteligente\u00a0"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.<\/p>\n<p>El alcalde de Ju\u00e1rez, Paco Trevi\u00f1o, entreg\u00f3 un apoyo de 200,000 pesos en una escuela primaria de la colonia Los Cometas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50768\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/IMG-20231129-WA0016-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/IMG-20231129-WA0016-300x169.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/IMG-20231129-WA0016-768x432.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/11\/IMG-20231129-WA0016.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>La directora del plantel, Anji R\u00edos, recibi\u00f3 el cheque de manos del edil en los patios de la escuela, acompa\u00f1ada de maestros y alumnos.<\/p>\n<p>En entrevista posterior al evento, el jefe de la comuna juarense, se\u00f1al\u00f3 que la escuela consigui\u00f3 un donativo de 35 computadoras de parte de la iniciativa privada, pero carec\u00edan de un lugar f\u00edsico para su instalaci\u00f3n y por ello, la administraci\u00f3n municipal se solidariz\u00f3 con el plantel y realiz\u00f3 la aportaci\u00f3n para la construcci\u00f3n del aula inteligente.<\/p>\n<p>Destac\u00f3 que aunque no es competencia del municipio suplir estas necesidades, su gobierno se solidariza con los ni\u00f1os juarenses para que tengan las mejores herramientas para su formaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L. El alcalde de Ju\u00e1rez, Paco Trevi\u00f1o, entreg\u00f3 un apoyo de 200,000 pesos en una escuela primaria de la colonia Los Cometas. &nbsp; &nbsp; La directora del plantel, Anji R\u00edos, recibi\u00f3 el cheque de manos del edil en los patios de la escuela, acompa\u00f1ada de maestros y alumnos. En entrevista posterior al evento, el [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":50767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[10761,3590,1684,5859],"class_list":["post-50766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-apoyo-aprimaria","tag-juarez-nl","tag-paco-trevino","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=50766"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50766\/revisions"}],"predecessor-version":[{"id":50769,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/50766\/revisions\/50769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/50767"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=50766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=50766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=50766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}