                       {"id":51122,"date":"2023-12-06T12:14:15","date_gmt":"2023-12-06T18:14:15","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=51122"},"modified":"2023-12-06T12:14:29","modified_gmt":"2023-12-06T18:14:29","slug":"hallan-cuerpo-calcinado-en-carretera-a-colombia-en-salinas-victoria","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/hallan-cuerpo-calcinado-en-carretera-a-colombia-en-salinas-victoria\/","title":{"rendered":"Hallan cuerpo calcinado en carretera a Colombia, en Salinas Victoria"},"content":{"rendered":"<p>Monterrey. &#8211; Este martes, un cuerpo calcinado fue encontrado a las orillas de una carretera en el municipio de Salinas Victoria, Nuevo Le\u00f3n.<\/p>\n<p>Los hechos ocurrieron en una brecha ubicada a la altura del kil\u00f3metro 18 de la Carretera a Colombia, lugar donde acudieron las autoridades alrededor de las 15:00 horas.<\/p>\n<p>Fueron polic\u00edas de Salinas Victoria quienes confirmaron el hallazgo del cuerpo, asimismo, agentes del Grupo de Homicidios de la Polic\u00eda Ministerial, tambi\u00e9n arribaron al sitio.<\/p>\n<p>Es importante mencionar, que la zona fue acordonada por las autoridades correspondientes y se espera que los peritos periciales realicen las indagatorias y ayuden a esclarecer los hechos.<\/p>\n<p>Hasta el momento, las autoridades no han revelado el sexo de la persona hallada, por lo tanto, se desconoce la identidad.<\/p>\n<p>FUENTE: ABC NOTICIAS<\/p>\n<p>Cr\u00e9ditos foto: abc noticias<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey. &#8211; Este martes, un cuerpo calcinado fue encontrado a las orillas de una carretera en el municipio de Salinas Victoria, Nuevo Le\u00f3n. Los hechos ocurrieron en una brecha ubicada a la altura del kil\u00f3metro 18 de la Carretera a Colombia, lugar donde acudieron las autoridades alrededor de las 15:00 horas. Fueron polic\u00edas de Salinas [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":51123,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[10845,10844,5595,5859],"class_list":["post-51122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-carreteracolombia-nuevoleon","tag-cuerpocalcinado","tag-salinasvictoria","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=51122"}],"version-history":[{"count":2,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51122\/revisions"}],"predecessor-version":[{"id":51125,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51122\/revisions\/51125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/51123"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=51122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=51122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=51122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}