                       {"id":51172,"date":"2023-12-07T08:40:26","date_gmt":"2023-12-07T14:40:26","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=51172"},"modified":"2023-12-07T08:40:26","modified_gmt":"2023-12-07T14:40:26","slug":"choca-camion-de-pasajeros-13-lesionados-el-saldo","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/choca-camion-de-pasajeros-13-lesionados-el-saldo\/","title":{"rendered":"Choca cami\u00f3n de pasajeros; 13 lesionados, el saldo"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.<\/p>\n<p>Un cami\u00f3n de transporte de personal, se impact\u00f3 contra un tope de contenci\u00f3n en la carretera a Reynosa, kil\u00f3metro 22, abajo del puente de Perif\u00e9rico, dejando un saldo de 13 personas lesionadas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-51174\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231207-WA0006-226x300.jpg\" alt=\"\" width=\"226\" height=\"300\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231207-WA0006-226x300.jpg 226w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231207-WA0006-771x1024.jpg 771w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231207-WA0006-768x1021.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231207-WA0006-1156x1536.jpg 1156w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231207-WA0006.jpg 1204w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" \/><\/p>\n<p>El operador no vio el peligroso tope que ya ha provocado varios accidentes y se impact\u00f3 de frente, con los resultados ya descritos.<\/p>\n<p>De los 13 heridos, fueron trasladados cuatro de ellos a varios hospitales, mientras que nueve ten\u00edan lesiones menores y prefirieron esperar el pase m\u00e9dico de la aseguradora.<\/p>\n<p>Los heridos que requirieron pronta atenci\u00f3n son: Francisco Villanueva Cruz, de 53 a\u00f1os de edad residente de la colonia Santa M\u00f3nica; Mar\u00eda Angela Ju\u00e1rez Acosta, de 50 a\u00f1os de la colonia Arcadia; Juliana Tovar Robles, de 36 a\u00f1os, con residencia en Viviendas Magdalenas y M\u00edriam Torres Reyes, de 48 a\u00f1os y con domicilio en la colonia Los Reguiletes.<\/p>\n<p>El conductor fue detenido, mientras se deslindan responsabilidades y se asegura la atenci\u00f3n m\u00e9dica de los lesionados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L. Un cami\u00f3n de transporte de personal, se impact\u00f3 contra un tope de contenci\u00f3n en la carretera a Reynosa, kil\u00f3metro 22, abajo del puente de Perif\u00e9rico, dejando un saldo de 13 personas lesionadas. &nbsp; &nbsp; El operador no vio el peligroso tope que ya ha provocado varios accidentes y se impact\u00f3 de frente, con [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":51173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[6012,541,3590,9378,5859],"class_list":["post-51172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-camion","tag-choque","tag-juarez-nl","tag-pasajeros","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=51172"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51172\/revisions"}],"predecessor-version":[{"id":51175,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51172\/revisions\/51175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/51173"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=51172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=51172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=51172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}