                       {"id":51516,"date":"2023-12-13T14:27:59","date_gmt":"2023-12-13T20:27:59","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=51516"},"modified":"2023-12-13T14:27:59","modified_gmt":"2023-12-13T20:27:59","slug":"trae-paco-trevino-el-mercado-de-la-gente-a-los-valles","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/trae-paco-trevino-el-mercado-de-la-gente-a-los-valles\/","title":{"rendered":"Trae Paco Trevi\u00f1o el mercado de la gente a los Valles"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.- El alcalde Paco Trevi\u00f1o, llev\u00f3 la ma\u00f1ana de hoy el \u201cMercado de la Gente\u201d a la colonia Los Valles en el municipio de Ju\u00e1rez.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-51518\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231213-WA0032-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231213-WA0032-300x225.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231213-WA0032-1024x768.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231213-WA0032-768x576.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231213-WA0032-1536x1152.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2023\/12\/IMG-20231213-WA0032.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Esto con la finalidad de que los vecinos de esa colonia puedan surtir su despensa b\u00e1sica a bajo costo como fruta y verdura de muy buena calidad, entre otros art\u00edculos.<\/p>\n<p>El edil tambi\u00e9n realiz\u00f3 una rifa de cinco cupones con valor de $200 pesos para que los ganadores pudieran intercambiarlos en el mismo &#8220;Mercado de la Gente&#8221; por lo que ellos quisieran.<\/p>\n<p>Asimismo, Paco Trevi\u00f1o aprovech\u00f3 para regalarles pelotas y bolsitas de dulces a los ni\u00f1os que se hicieron presentes en el lugar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- El alcalde Paco Trevi\u00f1o, llev\u00f3 la ma\u00f1ana de hoy el \u201cMercado de la Gente\u201d a la colonia Los Valles en el municipio de Ju\u00e1rez. &nbsp; &nbsp; &nbsp; &nbsp; Esto con la finalidad de que los vecinos de esa colonia puedan surtir su despensa b\u00e1sica a bajo costo como fruta y verdura de muy [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":51517,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[3590,1684,5859],"class_list":["post-51516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-juarez-nl","tag-paco-trevino","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=51516"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51516\/revisions"}],"predecessor-version":[{"id":51519,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51516\/revisions\/51519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/51517"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=51516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=51516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=51516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}