                       {"id":51617,"date":"2023-12-15T12:19:45","date_gmt":"2023-12-15T18:19:45","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=51617"},"modified":"2023-12-15T12:19:45","modified_gmt":"2023-12-15T18:19:45","slug":"explica-imss-sobre-fallecimiento-de-persona-en-sala-de-espera-de-hospital","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/explica-imss-sobre-fallecimiento-de-persona-en-sala-de-espera-de-hospital\/","title":{"rendered":"Explica IMSS sobre fallecimiento de persona en sala de espera de hospital"},"content":{"rendered":"<p>En torno a una fotograf\u00eda que circula en la red social X, en la que se observa una persona sentada, cubierta por una s\u00e1bana, en instalaciones hospitalarias, la coordinaci\u00f3n de Comunicaci\u00f3n Social en Colima, del Instituto Mexicano del Seguro Social (IMSS), inform\u00f3 que se trata del \u201cfallecimiento del familiar de un derechohabiente en la sala de Urgencias del HGZ 1 de Villa de \u00c1lvarez\u201d.<\/p>\n<p>Expuso en una tarjeta informativa que a las 15:50 horas de ayer, un hombre de la tercera edad, familiar de un derechohabiente que recib\u00eda atenci\u00f3n m\u00e9dica, falleci\u00f3 sentado en la sala de espera de Urgencias mientras esperaba la salida de su paciente.<\/p>\n<p>\u201cAl ser revisado por uno de los m\u00e9dicos de Urgencias y percatarse que no presentaba signos vitales, se procedi\u00f3 de inmediato a dar aviso al Ministerio P\u00fablico\u201d.<\/p>\n<p>El Instituto precis\u00f3 que colaborar\u00e1 con las instancias legales correspondientes para determinar las causas del deceso.<\/p>\n<p>Algunos internautas criticaron las \u201clargas esperas\u201d en el IMSS. Mientras que muchos asumieron que la persona estaba esperando ser atendida, lo cual fue negado por la instituci\u00f3n, pues se trat\u00f3 de alguien que acompa\u00f1aba a un derechohabiente.<\/p>\n<p>FUENTE: LA JORNADA<\/p>\n<p>Cr\u00e9ditos foto: la jornada<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En torno a una fotograf\u00eda que circula en la red social X, en la que se observa una persona sentada, cubierta por una s\u00e1bana, en instalaciones hospitalarias, la coordinaci\u00f3n de Comunicaci\u00f3n Social en Colima, del Instituto Mexicano del Seguro Social (IMSS), inform\u00f3 que se trata del \u201cfallecimiento del familiar de un derechohabiente en la sala [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":51618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[6657,1249,10987,10986,5859],"class_list":["post-51617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-fallecido","tag-imss","tag-saladeespera","tag-saladeurgencias","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=51617"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51617\/revisions"}],"predecessor-version":[{"id":51619,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/51617\/revisions\/51619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/51618"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=51617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=51617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=51617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}