                       {"id":52863,"date":"2024-01-12T03:05:25","date_gmt":"2024-01-12T09:05:25","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=52863"},"modified":"2024-01-12T03:06:47","modified_gmt":"2024-01-12T09:06:47","slug":"le-quitan-la-vida-de-cinco-balazos","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/le-quitan-la-vida-de-cinco-balazos\/","title":{"rendered":"Le quitan la vida de cinco balazos"},"content":{"rendered":"\n<p><br>Ju\u00e1rez, N.L.-<br>Un hombre perdi\u00f3 la vida a manos de sus ejecutores en la colonia H\u00e9roe de Nacozari, la noche de ayer.<br>Seg\u00fan los primeros informes, la v\u00edctima fue identificada como Reyes Ramiro Sep\u00falveda Santos, de 32 a\u00f1os de edad, quien fue ultimado de cinco balazos en la calle Hermenegildo Galeana en la mencionada colonia.<br>Seg\u00fan testigos, Sep\u00falveda Santos se encontraba en el interior de su casa, cuando alguien lo llam\u00f3 del exterior para que saliera y fue cuando recibi\u00f3 cinco disparos de arma de fuego.<br>El cuerpo del herido cay\u00f3 a un lado de un taxi que tambi\u00e9n fue alcanzado por las balas, donde falleci\u00f3 a los pocos minutos.<br>El cuerpo sin vida de la v\u00edctima vest\u00eda pants color negros, tenis negros y playera gris y a pocos metros quedaron ochos casquillos de arma corta percutidos y una ojiva, que fueron recogidos por Servicios Periciales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.-Un hombre perdi\u00f3 la vida a manos de sus ejecutores en la colonia H\u00e9roe de Nacozari, la noche de ayer.Seg\u00fan los primeros informes, la v\u00edctima fue identificada como Reyes Ramiro Sep\u00falveda Santos, de 32 a\u00f1os de edad, quien fue ultimado de cinco balazos en la calle Hermenegildo Galeana en la mencionada colonia.Seg\u00fan testigos, Sep\u00falveda [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":52862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[4415,4351,917,1355],"class_list":["post-52863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-ataque-a-balazos","tag-balazos","tag-ejecutado","tag-juarez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/52863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=52863"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/52863\/revisions"}],"predecessor-version":[{"id":52864,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/52863\/revisions\/52864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/52862"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=52863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=52863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=52863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}