                       {"id":53587,"date":"2024-01-25T12:30:05","date_gmt":"2024-01-25T18:30:05","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=53587"},"modified":"2024-01-25T12:30:05","modified_gmt":"2024-01-25T18:30:05","slug":"firma-imss-nuevo-leon-convenio-para-abrir-primera-guarderia-en-empresa-en-el-estado","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/firma-imss-nuevo-leon-convenio-para-abrir-primera-guarderia-en-empresa-en-el-estado\/","title":{"rendered":"Firma IMSS Nuevo Le\u00f3n convenio para abrir primera Guarder\u00eda en Empresa en el estado"},"content":{"rendered":"<p>\u2022 El Seguro Social de Nuevo Le\u00f3n firm\u00f3 el primer convenio en el estado con empresas privadas para que presten el servicio de guarder\u00eda para atender a hijas e hijos de sus propios trabajadores.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-53590\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0665-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0665-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0665-1024x683.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0665-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0665-1536x1024.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0665.jpg 1620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>\u2022 El evento lo encabezaron el titular del IMSS en la entidad, doctor Tonatihu Ortiz Castillo, y los representantes de las dos empresas firmantes.<\/p>\n<p>El Instituto Mexicano del Seguro Social en Nuevo Le\u00f3n (IMSS) llev\u00f3 a cabo la firma de un convenio para instalar en 2024 la primera guarder\u00eda en Empresa en el estado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-53591\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0662-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0662-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0662-1024x683.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0662-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0662-1536x1024.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/01\/DSC0662.jpg 1620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>El Seguro Social firm\u00f3 el convenio con las empresas Curtidos Trevi\u00f1o S.A. de C.V. y Oportunidades el Carmen, A.C. para que construyan instalaciones apropiadas y de manera directa otorguen el servicio de guarder\u00edas a las hijas e hijos de su personal.<\/p>\n<p>En representaci\u00f3n del IMSS Nuevo Le\u00f3n, firmaron el convenio su Titular, Dr. Tonatihu Ortiz Castillo, y el Jefe de Servicios de Salud en el Trabajo, Prestaciones Econ\u00f3micas y Sociales, Lic. Jos\u00e9 Roberto Mansur Debernardi. Por las empresas, firmaron el documento el Lic. Sergio Mendoza Cant\u00fa y el Lic. Rosendo Agust\u00edn Beltr\u00e1n.<\/p>\n<p>Con el acuerdo, las empresas se comprometen a contar con un espacio adecuado cercano a sus instalaciones que cumpla con toda la normatividad y las medidas de seguridad establecidas por el Instituto. Podr\u00e1n otorgar el servicio de guarder\u00eda a partir del 1 de junio, con una capacidad instalada de 252 lugares para ni\u00f1as y ni\u00f1os en edades entre 43 d\u00edas y 4 a\u00f1os, en un horario de 06:00 a 20:00 horas.<\/p>\n<p>As\u00ed como en los dem\u00e1s esquemas de prestaci\u00f3n del servicio de guarder\u00eda del Instituto, la representaci\u00f3n del IMSS en el estado supervisar\u00e1 y vigilar\u00e1 el otorgamiento del servicio bajo las normas establecidas de seguridad, formaci\u00f3n y bienestar de los menores, en condiciones \u00f3ptimas con personal capacitado, certificado y especializado.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 El Seguro Social de Nuevo Le\u00f3n firm\u00f3 el primer convenio en el estado con empresas privadas para que presten el servicio de guarder\u00eda para atender a hijas e hijos de sus propios trabajadores. &nbsp; &nbsp; \u2022 El evento lo encabezaron el titular del IMSS en la entidad, doctor Tonatihu Ortiz Castillo, y los representantes [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":53589,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[11507,11508,7783,1249,5859,10411],"class_list":["post-53587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-convenio","tag-empresaenelestado","tag-guarderia","tag-imss","tag-ultimas-noticias","tag-ultimasnoticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/53587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=53587"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/53587\/revisions"}],"predecessor-version":[{"id":53592,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/53587\/revisions\/53592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/53589"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=53587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=53587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=53587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}