                       {"id":54122,"date":"2024-02-04T02:10:08","date_gmt":"2024-02-04T08:10:08","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=54122"},"modified":"2024-02-04T02:12:04","modified_gmt":"2024-02-04T08:12:04","slug":"pierde-la-vida-joven-en-atropello-responsable-se-da-a-la-fuga","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/pierde-la-vida-joven-en-atropello-responsable-se-da-a-la-fuga\/","title":{"rendered":"Pierde la vida joven en atropello; responsable se da a la fuga"},"content":{"rendered":"\n<p>Ju\u00e1rez, N.L.-La noche del s\u00e1bado, un joven perdi\u00f3 la vida al ser atropellado en la avenida Reynosa en su cruce con Ebanitos, en el municipio de Ju\u00e1rez.<br \/>El reporte se registr\u00f3 alrededor de las 9:00 de la noche, donde se mencionaba a un joven en medio del carril lesionado, al arribo de param\u00e9dicos de Protecci\u00f3n Civil de Ju\u00e1rez, dictaminaron que ya no contaba con signos vitales.<br \/>El ahora occiso que hasta el momento no ha sido identificado, vest\u00eda un short en color gris con laterales verde fosforescente y camisa blanca, tendr\u00eda una edad de entre los 16 y 20 a\u00f1os de edad.<br \/>El lugar fue acordonado por Tr\u00e1nsito del Municipio, mientras la Polic\u00eda Municipal realizaba recorridos para tratar de dar con el responsable del atropello, quien se dio a la fuga desconoci\u00e9ndose hasta el momento su paradero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.-La noche del s\u00e1bado, un joven perdi\u00f3 la vida al ser atropellado en la avenida Reynosa en su cruce con Ebanitos, en el municipio de Ju\u00e1rez.El reporte se registr\u00f3 alrededor de las 9:00 de la noche, donde se mencionaba a un joven en medio del carril lesionado, al arribo de param\u00e9dicos de Protecci\u00f3n Civil [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":54121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[219,11638,11639],"class_list":["post-54122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-juarez","tag-atropellado","tag-joven-pierde-la-vida","tag-responsable-se-da-a-la-fuga"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/54122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=54122"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/54122\/revisions"}],"predecessor-version":[{"id":54123,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/54122\/revisions\/54123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/54121"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=54122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=54122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=54122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}