                       {"id":54486,"date":"2024-02-13T12:28:27","date_gmt":"2024-02-13T18:28:27","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=54486"},"modified":"2024-02-13T12:28:27","modified_gmt":"2024-02-13T18:28:27","slug":"estrena-imss-nuevo-leon-nuevo-equipo-de-resonancia-magnetica-nuclear-en-el-hgz-no-67","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/estrena-imss-nuevo-leon-nuevo-equipo-de-resonancia-magnetica-nuclear-en-el-hgz-no-67\/","title":{"rendered":"Estrena IMSS Nuevo Le\u00f3n nuevo equipo de resonancia magn\u00e9tica nuclear en el HGZ No. 67"},"content":{"rendered":"<p>\u2022 Invierte Instituto m\u00e1s de 54 millones de pesos en este equipo de alta tecnolog\u00eda.<\/p>\n<p>\u2022 Incrementa Seguro Social en la entidad su capacidad para realizar diagn\u00f3sticos m\u00e1s precisos en Traumatolog\u00eda, Cardiolog\u00eda, Neurolog\u00eda, Oncolog\u00eda, entre otras especialidades.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-54488\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/02\/DSC0039-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/02\/DSC0039-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/02\/DSC0039-1024x683.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/02\/DSC0039-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/02\/DSC0039-1536x1024.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/02\/DSC0039.jpg 1620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>\u2022 Favorece resonador a una poblaci\u00f3n superior a los 2 millones de derechohabientes.<\/p>\n<p>&nbsp;<\/p>\n<p>Con una inversi\u00f3n de 54 millones 906 mil 588 pesos, a partir de este mes, entr\u00f3 en operaci\u00f3n un equipo de Resonancia Magn\u00e9tica Nuclear (RMN) para el Hospital General de Zona (HGZ) No. 67 del Instituto Mexicano del Seguro Social (IMSS) en Apodaca, Nuevo Le\u00f3n.<\/p>\n<p>El equipo de alta tecnolog\u00eda, que fue inaugurado en la reciente gira del director general del IMSS, Maestro Zo\u00e9 Robledo, aumenta la capacidad instalada para estudios de alta precisi\u00f3n necesarios en el diagn\u00f3stico de enfermedades.<\/p>\n<p>Un nuevo resonador en el HGZ No. 67 ser\u00e1 de gran apoyo para el servicio que ven\u00eda otorgando el HGZ No. 33, que tan s\u00f3lo en el 2023 realiz\u00f3 4 mil 166 estudios.<\/p>\n<p>La poblaci\u00f3n beneficiada ascender\u00e1 a 2 millones 335 mil 514 derechohabientes de Apodaca, Guadalupe y San Nicol\u00e1s de los Garza.<\/p>\n<p>Su uso ser\u00e1 un gran soporte para diagn\u00f3sticos cl\u00ednicos de especialidades m\u00e9dicas de Traumatolog\u00eda, Cardiolog\u00eda, Angiolog\u00eda, Neurolog\u00eda, Neurocirug\u00eda, Oncolog\u00eda y Cirug\u00eda General, entre otras.<\/p>\n<p>Con esto, el IMSS mantiene su compromiso de otorgar un servicio de calidad, calidez y con oportunidad, gracias a su inversi\u00f3n en nuevas tecnolog\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Invierte Instituto m\u00e1s de 54 millones de pesos en este equipo de alta tecnolog\u00eda. \u2022 Incrementa Seguro Social en la entidad su capacidad para realizar diagn\u00f3sticos m\u00e1s precisos en Traumatolog\u00eda, Cardiolog\u00eda, Neurolog\u00eda, Oncolog\u00eda, entre otras especialidades. &nbsp; &nbsp; \u2022 Favorece resonador a una poblaci\u00f3n superior a los 2 millones de derechohabientes. &nbsp; Con una [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":54487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[11711,1249,11712],"class_list":["post-54486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-equipo-nuevo","tag-imss","tag-resonancia-magnetica-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/54486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=54486"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/54486\/revisions"}],"predecessor-version":[{"id":54489,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/54486\/revisions\/54489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/54487"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=54486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=54486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=54486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}