                       {"id":55501,"date":"2024-03-08T12:58:14","date_gmt":"2024-03-08T18:58:14","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=55501"},"modified":"2024-03-08T12:58:17","modified_gmt":"2024-03-08T18:58:17","slug":"hacen-justicia-por-sus-propias-mano-y-detienen-a-presunto-ladron-en-juarez","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/hacen-justicia-por-sus-propias-mano-y-detienen-a-presunto-ladron-en-juarez\/","title":{"rendered":"Hacen justicia por sus propias mano y detienen a presunto ladr\u00f3n en Ju\u00e1rez"},"content":{"rendered":"\n<p><br><br>Ju\u00e1rez, N.L.- Un hombre el cual presuntamente intent\u00f3 robar en un domicilio, fue sometido, golpeado y amarrado por vecinos de la colonia Bosques del Seminario, en el municipio de Ju\u00e1rez. <br>Los hechos ocurrieron cerca de las 7:00 de la ma\u00f1ana, en la calle Robles en su cruce con Pinos en el segundo sector de la colonia antes mencionada. <br>Seg\u00fan vecinos el hombre acompa\u00f1ado de una mujer, intentaron ingresar a un domicilio, sin embargo el due\u00f1o se percat\u00f3 de la presencia de los intrusos y salieron corriendo. <br>El due\u00f1o de la vivienda pidi\u00f3 apoyo de los vecinos y poncharon la motocicleta, la cual dej\u00f3 en su intento de huida. <br>Minutos despu\u00e9s el presunto ladr\u00f3n trat\u00f3 de recuperar la motocicleta, pero los enardecidos vecinos lo sometieron, le propiciaron algunos, lo amarraron y llamaron a las autoridades.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"583\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/03\/img-20240308-wa00084959878998685777668-1024x583.jpg\" alt=\"\" class=\"wp-image-55500\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/03\/img-20240308-wa00084959878998685777668-1024x583.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/03\/img-20240308-wa00084959878998685777668-300x171.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/03\/img-20240308-wa00084959878998685777668-768x437.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/03\/img-20240308-wa00084959878998685777668.jpg 1058w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Un hombre el cual presuntamente intent\u00f3 robar en un domicilio, fue sometido, golpeado y amarrado por vecinos de la colonia Bosques del Seminario, en el municipio de Ju\u00e1rez. Los hechos ocurrieron cerca de las 7:00 de la ma\u00f1ana, en la calle Robles en su cruce con Pinos en el segundo sector de la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":55499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,10],"tags":[11920,3590,5859],"class_list":["post-55501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad-juarez","tag-hacen-justicia","tag-juarez-nl","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/55501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=55501"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/55501\/revisions"}],"predecessor-version":[{"id":55502,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/55501\/revisions\/55502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/55499"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=55501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=55501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=55501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}