                       {"id":56417,"date":"2024-04-09T22:12:26","date_gmt":"2024-04-10T04:12:26","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=56417"},"modified":"2024-04-09T22:14:07","modified_gmt":"2024-04-10T04:14:07","slug":"motociclista-resulta-lesionado-en-accidente-vial","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/motociclista-resulta-lesionado-en-accidente-vial\/","title":{"rendered":"Motociclista resulta lesionado en accidente vial"},"content":{"rendered":"\n<p>Cadereyta Jim\u00e9nez, N.L.- La noche de este martes, un motociclista result\u00f3 lesionado tras ser impactado por la conductora de una camioneta, en el municipio de Cadereyta.<br \/>El percance se registr\u00f3 en el boulevard Revoluci\u00f3n justo en la entrada de Bodega Aurrera.<br \/>El motociclista identificado como Cesar Adiel de 21 a\u00f1os de edad, fue impactado por la conductora de una camioneta tipo Terrain de color gris, por lo que result\u00f3 con algunas lesiones afortunadamente nada de gravedad.<br \/>Param\u00e9dicos de Servicios de Emergencia trasladaron al lesionado a la cl\u00ednica 14 del IMSS para su atenci\u00f3n m\u00e9dica.<br \/>Agentes de Vialidad y Tr\u00e1nsito arribaron al sitio para realizar las indagatorias correspondientes y deslindar responsabilidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- La noche de este martes, un motociclista result\u00f3 lesionado tras ser impactado por la conductora de una camioneta, en el municipio de Cadereyta.El percance se registr\u00f3 en el boulevard Revoluci\u00f3n justo en la entrada de Bodega Aurrera.El motociclista identificado como Cesar Adiel de 21 a\u00f1os de edad, fue impactado por la conductora [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":56416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[4196,2600,5450,4315],"class_list":["post-56417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-cadereyta","tag-accidente","tag-cadereyta","tag-choca-a-motociclista","tag-lesionados"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/56417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=56417"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/56417\/revisions"}],"predecessor-version":[{"id":56418,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/56417\/revisions\/56418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/56416"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=56417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=56417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=56417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}