                       {"id":56856,"date":"2024-04-23T14:43:36","date_gmt":"2024-04-23T20:43:36","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=56856"},"modified":"2024-04-23T14:43:54","modified_gmt":"2024-04-23T20:43:54","slug":"corta-la-existencia-a-su-ex-mujer","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/corta-la-existencia-a-su-ex-mujer\/","title":{"rendered":"Corta la existencia a su ex mujer"},"content":{"rendered":"\n<p><br><br>Ju\u00e1rez, N.L.- Un amargo despertar tuvieron dos hermanos de la colonia Ampliaci\u00f3n Rancho Viejo, al descubrir el cuerpo de su madre ya sin vida, quien presuntamente fue asesinada por su ex pareja. <br>El cuerpo de Alma Delia Due\u00f1ez&nbsp; Alvarado de 44 a\u00f1os de edad, fue encontrada con varias heridas de arma blanca y con una cuerda en color gris en su rec\u00e1mara.<br>El presunto responsable pudiera ser su ex pareja de Jos\u00e9 Merced C. de 49 a\u00f1os de edad, padre de sus cuatro hijos y de quien ten\u00eda un a\u00f1o separada. <br>Sin embargo, el hombre lleg\u00f3 el d\u00eda de ayer, a la vivienda a un convivio con su familia donde posteriormente se desencadenaron los lamentables hechos.<br>El presunto homicida se entreg\u00f3 a las autoridades despu\u00e9s del ataque, adem\u00e1s presentaba lesiones, ya que intent\u00f3 quitarse la vida.<br>Al lugar arribaron Agentes Ministeriales y Servicios Periciales quienes, comenzaron las investigaciones correspondientes de tan lamentable crimen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00175082871262086391658-1024x768.jpg\" alt=\"\" class=\"wp-image-56854\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00175082871262086391658-1024x768.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00175082871262086391658-300x225.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00175082871262086391658-768x576.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00175082871262086391658-1536x1152.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00175082871262086391658.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00207878416227224384430-300x300.jpg\" alt=\"\" class=\"wp-image-56855\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00207878416227224384430-300x300.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00207878416227224384430-150x150.jpg 150w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00207878416227224384430-768x768.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00207878416227224384430-80x80.jpg 80w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/04\/img-20240423-wa00207878416227224384430.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.- Un amargo despertar tuvieron dos hermanos de la colonia Ampliaci\u00f3n Rancho Viejo, al descubrir el cuerpo de su madre ya sin vida, quien presuntamente fue asesinada por su ex pareja. El cuerpo de Alma Delia Due\u00f1ez&nbsp; Alvarado de 44 a\u00f1os de edad, fue encontrada con varias heridas de arma blanca y con una [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":56853,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,10],"tags":[12114,3590,4357,5859],"class_list":["post-56856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad-juarez","tag-asesina-a-su-ex-mujer","tag-juarez-nl","tag-muerte","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/56856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=56856"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/56856\/revisions"}],"predecessor-version":[{"id":56857,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/56856\/revisions\/56857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/56853"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=56856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=56856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=56856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}