                       {"id":56956,"date":"2024-04-25T19:18:59","date_gmt":"2024-04-26T01:18:59","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=56956"},"modified":"2024-04-25T19:20:35","modified_gmt":"2024-04-26T01:20:35","slug":"roba-menor-camioneta-y-lo-detienen","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/roba-menor-camioneta-y-lo-detienen\/","title":{"rendered":"Roba menor camioneta y lo detienen"},"content":{"rendered":"\n<p>Cadereyta Jim\u00e9nez, N.L.- La ma\u00f1ana de este jueves, un menor de edad, fue detenido por elementos de la Polic\u00eda Municipal de Cadereyta, tras haber robado una camioneta y ser detectado.<br \/>El menor identificado como \u00c1ngel de 17 a\u00f1os de edad, quien presuntamente vino desde Pesquer\u00eda, rob\u00f3 una camioneta Volkswagen de color blanco de reciente modelo, en la Purisima.<br \/>Tras recibir el reporte e iniciar la b\u00fasqueda los efectivos municipales detectaron la camioneta, en la carretera Cadereyta-Allende en el entronque con el libramiento Alfonso Mart\u00ednez Dom\u00ednguez, en ese sitio le marcaron el alto al joven, el cual descendi\u00f3 de la camioneta e intent\u00f3 correr entre la maleza, pero fue copado.<br \/>El menor fue puesto a disposici\u00f3n del Ministerio P\u00fablico, por el delito de robo de veh\u00edculo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- La ma\u00f1ana de este jueves, un menor de edad, fue detenido por elementos de la Polic\u00eda Municipal de Cadereyta, tras haber robado una camioneta y ser detectado.El menor identificado como \u00c1ngel de 17 a\u00f1os de edad, quien presuntamente vino desde Pesquer\u00eda, rob\u00f3 una camioneta Volkswagen de color blanco de reciente modelo, en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":56955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[8693,819,9842],"class_list":["post-56956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad-cadereyta","tag-delito-de-robo","tag-detenido","tag-roba-camioneta"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/56956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=56956"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/56956\/revisions"}],"predecessor-version":[{"id":56957,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/56956\/revisions\/56957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/56955"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=56956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=56956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=56956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}