                       {"id":58155,"date":"2024-06-11T16:05:20","date_gmt":"2024-06-11T22:05:20","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=58155"},"modified":"2024-06-11T16:05:20","modified_gmt":"2024-06-11T22:05:20","slug":"por-poco-linchan-a-exhibicionista-acosador","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/por-poco-linchan-a-exhibicionista-acosador\/","title":{"rendered":"Por poco linchan a exhibicionista acosador"},"content":{"rendered":"\n<p><br>Ju\u00e1rez, N.L.<br>Un hombre acusado por los vecinos de acosar a las mujeres de la calle R\u00edo Chao de la colonia Privadas Ocania, estuvo a punto de ser linchado por un grupo de residentes del lugar, enojados por el proceder del sujeto.<br>Identificado como Alejandro C. De 42 a\u00f1os de edad, el acusado, quien dijo ser guardia de seguridad, se encontraba dentro de su casa, cuando esta fue rodeada por decenas de vecinos, quienes le exig\u00edan&nbsp; que saliera.<br>La pareja del sujeto al enterarse de lo que hac\u00ed, lo oblig\u00f3 a salir, cuando en la puerta de la casa lo detuvo la polic\u00eda municipal&nbsp; de Ju\u00e1rez.<br>Los uniformados lo trasladaron al CODE, mientras los airados habitantes de esa calle interpon\u00edan la denuncia respectiva y entregban los videos donde sal\u00eda sin ropa fuera de su casa y se tomaba testimonio de acosos sexual a varias mujeres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L.Un hombre acusado por los vecinos de acosar a las mujeres de la calle R\u00edo Chao de la colonia Privadas Ocania, estuvo a punto de ser linchado por un grupo de residentes del lugar, enojados por el proceder del sujeto.Identificado como Alejandro C. De 42 a\u00f1os de edad, el acusado, quien dijo ser guardia [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":58154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[52,3590,5859],"class_list":["post-58155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-acosador","tag-juarez-nl","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/58155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=58155"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/58155\/revisions"}],"predecessor-version":[{"id":58156,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/58155\/revisions\/58156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/58154"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=58155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=58155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=58155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}